{"id":249738,"date":"2025-09-03T12:47:23","date_gmt":"2025-09-03T10:47:23","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=249738"},"modified":"2025-09-03T12:47:23","modified_gmt":"2025-09-03T10:47:23","slug":"sanita-leoci-il-nostro-sistema-regionale-ancora-una-volta-promosso-da-gimbe","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/sanita-leoci-il-nostro-sistema-regionale-ancora-una-volta-promosso-da-gimbe\/","title":{"rendered":"Sanit\u00e0, Leoci: \u201cIl nostro sistema regionale ancora una volta promosso da Gimbe\u201d"},"content":{"rendered":"<p>\u201cAccogliamo con grande soddisfazione i dati diffusi dalla Fondazione Gimbe relativi al monitoraggio 2023 dei Livelli essenziali di assistenza (Lea), che certificano come la Puglia sia tra le Regioni italiane che hanno rispettato gli standard fissati dal Ministero della Salute. Con un punteggio di 228, in crescita rispetto al 2022, la nostra Regione si colloca al decimo posto in Italia, dimostrando di saper garantire cure di qualit\u00e0 ai cittadini.\u201d Lo afferma in una nota il capogruppo di CON, il consigliere regionale Alessandro Leoci.<\/p>\n<p>\u201cQuesto risultato \u2013 prosegue -, frutto di un lavoro costante e di una programmazione attenta, conferma che la maggioranza di centrosinistra \u00e8 in grado di assicurare una sanit\u00e0 di livello, capace di rispondere ai bisogni di salute della popolazione pugliese. Nonostante le difficolt\u00e0 nazionali e le sfide che il sistema sanitario affronta ogni giorno, la Puglia si distingue per aver rispettato gli indicatori in tutte le aree monitorate: prevenzione collettiva, assistenza distrettuale e ospedaliera.\u201d<\/p>\n<p>\u201cIl dato che ci vede crescere rispetto all\u2019anno precedente \u2013 conclude il capogruppo di CON, &#8211; \u00e8 particolarmente significativo: vuol dire che stiamo andando nella direzione giusta, investendo risorse, energie e professionalit\u00e0 per rafforzare la rete sanitaria regionale. Continueremo a lavorare per migliorare ancora, consapevoli che la salute dei pugliesi \u00e8 e deve restare al centro dell\u2019azione politica e amministrativa\u201d.\/comunicato<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAccogliamo con grande soddisfazione i dati diffusi dalla Fondazione Gimbe relativi al monitoraggio 2023 dei Livelli essenziali di assistenza (Lea), che certificano come la Puglia sia tra le Regioni italiane che hanno rispettato gli standard fissati dal Ministero della Salute. Con un punteggio di 228, in crescita rispetto al 2022, la nostra Regione si colloca al decimo posto in Italia, dimostrando di saper garantire cure di qualit\u00e0 ai cittadini.\u201d Lo afferma in una nota il capogruppo di CON, il consigliere regionale Alessandro Leoci. \u201cQuesto risultato \u2013 prosegue -, frutto di un lavoro costante e di una programmazione attenta, conferma che la maggioranza di centrosinistra \u00e8 in grado di assicurare una sanit\u00e0 di livello, capace di rispondere ai bisogni di salute della popolazione pugliese. Nonostante le difficolt\u00e0 nazionali e le sfide che il sistema sanitario affronta ogni giorno, la Puglia si distingue per aver rispettato gli indicatori in tutte le aree monitorate: prevenzione collettiva, assistenza distrettuale e ospedaliera.\u201d \u201cIl dato che ci vede crescere rispetto all\u2019anno precedente \u2013 conclude il capogruppo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":216325,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-249738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/249738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=249738"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/249738\/revisions"}],"predecessor-version":[{"id":249739,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/249738\/revisions\/249739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/216325"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=249738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=249738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=249738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}