{"id":249769,"date":"2025-09-04T10:26:57","date_gmt":"2025-09-04T08:26:57","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=249769"},"modified":"2025-09-04T10:26:57","modified_gmt":"2025-09-04T08:26:57","slug":"foritica-nuovo-appuntamento-al-parco-buscicchio-in-scena-zanna-bianca-con-luigi-delia","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/foritica-nuovo-appuntamento-al-parco-buscicchio-in-scena-zanna-bianca-con-luigi-delia\/","title":{"rendered":"Foritic\u00e0, nuovo appuntamento al Parco Buscicchio: in scena \u201cZanna Bianca\u201d con Luigi D\u2019Elia"},"content":{"rendered":"\n<p>Dopo l\u2019entusiasmante debutto, Parco Buscicchio accoglie il secondo appuntamento della rassegna Foritic\u00e0 &#8211; Il Teatro nel Parco. In programma, venerd\u00ec 5 settembre, alle ore 20,30, \u201cZanna Bianca\u201d con Luigi D\u2019Elia.<\/p>\n<p>Lo spettacolo \u00e8 un viaggio teatrale nel cuore selvaggio del Grande Nord. Luigi D\u2019Elia, con la drammaturgia di Francesco Niccolini, d\u00e0 corpo e voce al celebre romanzo di Jack London in una pi\u00e8ce teatrale fisica e sensoriale, fatta di silenzi, suoni e immagini evocative. In scena l\u2019attore diventa neve, foresta, fiume e lupo, trascinando il pubblico in un racconto che \u00e8 insieme avventura, metafora della vita e ritorno alle radici pi\u00f9 profonde della natura. Le scene, scolpite e costruite dallo stesso D\u2019Elia e le luci di Paolo Mongelli, completano un affresco potente, capace di emozionare spettatori di ogni et\u00e0 con energia vitale, poesia e libert\u00e0.<\/p>\n<p>Con il riconoscimento dell\u2019EoloAwards 2019 come Miglior Spettacolo e del Festeb\u00e0 2019, l\u2019opera si distingue nel panorama del teatro di narrazione contemporaneo per la sua forza poetica e la capacit\u00e0 di emozionare spettatori di ogni et\u00e0.<\/p>\n<p>L\u2019ingresso \u00e8 libero e gratuito. \u00c8 possibile comunicare la propria partecipazione al link: https:\/\/short-link.me\/18wqw<\/p>\n<p>Nella stessa giornata, dalle ore 17,30 alle 19,30, Luigi D\u2019Elia d\u00e0 il via a S\u00e8mina, il ciclo di workshop a cura di attori e attrici ospiti della rassegna, promosso da SEM \u2013 Sant\u2019Elia Malat\u00eca &#8211; Scuola popolare di teatro e arti urbane, rivolto ad attori, allievi, appassionati, scrittori. L\u2019incontro, dal titolo \u201cDove nasce un fuoco: rigenerare spazi creativi\u201d, \u00e8 un laboratorio di scrittura scenica nella forma del monologo che, attraverso segni, tracce e vibrazioni di una ricerca teatrale nata proprio a Brindisi, invita i partecipanti a chiedersi cosa valga la pena raccontare oggi e a piantare il primo seme di un possibile racconto personale.<\/p>\n<p>Per partecipare al workshop \u00e8 necessario prenotarsi al link: https:\/\/short-link.me\/1d2mq<\/p>\n<p>Foritic\u00e0 &#8211; Il Teatro nel Parco \u00e8 promosso nell\u2019ambito di \u201cSEM \u2013 Sant\u2019Elia Malat\u00eca, scuola popolare di teatro e arti urbane\u201d le cui attivit\u00e0 si svolgono nella Casa di Quartiere di Parco Buscicchio e che apre al pubblico con una programmazione culturale pensata per intrecciare linguaggi diversi sperimentando nuove forme di espressione performativa e visiva. La rassegna \u00e8 ideata per avvicinare cittadini e attori in erba al mondo del teatro e della cultura, creando nuove occasioni di incontro e partecipazione nelle periferie. L\u2019iniziativa offre momenti di fruizione culturale a chi desidera vivere esperienze artistiche di qualit\u00e0. In programma, a partire dal mese di agosto, cinque appuntamenti che portano in scena alcune tra le realt\u00e0 pi\u00f9 apprezzate del panorama teatrale italiano.<\/p>\n<p>Foritic\u00e0 \u2013 Il teatro nel parco promuove protagonismo, linguaggi e relazioni per favorire comunit\u00e0, inclusione e coesione sociale. Il nuovo Teatro nel parco, frutto di un\u2019azione collettiva, trasforma un\u2019area sottoutilizzata in uno spazio inclusivo dove tutti possono esprimersi e sperimentare l\u2019arte davanti a un pubblico, diventando simbolo di rigenerazione urbana e sociale.<\/p>\n<p>I prossimi spettacoli in programma: il 12 settembre con la Compagnia Orsini, realt\u00e0 di spicco del teatro contemporaneo (tra i riconoscimenti anche il Premio Ubu 2024), che presenta \u201cSete\u201d di Walter Prete, regia di Lorenzo Parrotto, con Giorgio Sales in uno spettacolo che unisce scrittura autoriale e interpretazione scenica in un equilibrio di rigore e intensit\u00e0; venerd\u00ec 26 settembre Daria Paoletta della compagnia Buramb\u00f2 con \u201cAmore e Psiche\u201d (Premio Eolo Awards 2015), racconto che rilegge il mito classico restituendone la forza universale; venerd\u00ec 3 ottobre con \u201cV\u00ectV\u00ect! Storia di una pendolare\u201d di Francesca Danese, artista che unisce sensibilit\u00e0 stilistica e sperimentazione contemporanea, dando vita a un lavoro originale e coinvolgente, capace di parlare al pubblico con un linguaggio personale e diretto.<\/p>\n<p>Il progetto \u201cSEM &#8211; Sant\u2019Elia Malatia &#8211; Scuola popolare di teatro e arti urbane\u201d \u00e8 promosso e finanziato da Puglia Culture con il programma di Welfare Culturale del Dipartimento Turismo, Economia della Cultura e Valorizzazione del Territorio della Regione Puglia. La rassegna fa parte delle azioni del progetto pilota della Regione Puglia, Dipartimento Turismo e Cultura, che vede quello di Brindisi, a cura dell\u2019impresa sociale ImmaginAbile, tra i due progetti finanziati per dettare le linee guida sul welfare culturale regionale nel prossimo triennio.<\/p>\n<p>Tutti gli spettacoli sono in programma alle ore 20,30 presso Parco Buscicchio (via A. Mantegna, 10, Brindisi). L\u2019ingresso \u00e8 libero e gratuito.<\/p>\n<p>\u00c8 possibile comunicare la propria partecipazione attivando il biglietto virtuale allo spettacolo \u201cZanna Bianca\u201d al link: https:\/\/short-link.me\/18wqw<\/p>\n<p>Il biglietto virtuale non garantisce il posto a sedere, \u00e8 uno strumento utile a fornire all\u2019organizzazione dati sull\u2019affluenza.<\/p>\n<p>\u00c8 possibile prenotare il workshop al link: https:\/\/short-link.me\/1d2mq<\/p>\n<p>Il programma aggiornato \u00e8 disponibile sui canali social Collettivo ImmaginAbile e Legami di Comunit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo l\u2019entusiasmante debutto, Parco Buscicchio accoglie il secondo appuntamento della rassegna Foritic\u00e0 &#8211; Il Teatro nel Parco. In programma, venerd\u00ec 5 settembre, alle ore 20,30, \u201cZanna Bianca\u201d con Luigi D\u2019Elia. Lo spettacolo \u00e8 un viaggio teatrale nel cuore selvaggio del Grande Nord. Luigi D\u2019Elia, con la drammaturgia di Francesco Niccolini, d\u00e0 corpo e voce al celebre romanzo di Jack London in una pi\u00e8ce teatrale fisica e sensoriale, fatta di silenzi, suoni e immagini evocative. In scena l\u2019attore diventa neve, foresta, fiume e lupo, trascinando il pubblico in un racconto che \u00e8 insieme avventura, metafora della vita e ritorno alle radici pi\u00f9 profonde della natura. Le scene, scolpite e costruite dallo stesso D\u2019Elia e le luci di Paolo Mongelli, completano un affresco potente, capace di emozionare spettatori di ogni et\u00e0 con energia vitale, poesia e libert\u00e0. Con il riconoscimento dell\u2019EoloAwards 2019 come Miglior Spettacolo e del Festeb\u00e0 2019, l\u2019opera si distingue nel panorama del teatro di narrazione contemporaneo per la sua forza poetica e la capacit\u00e0 di emozionare spettatori di ogni&#8230;<\/p>\n","protected":false},"author":2,"featured_media":143137,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,162],"tags":[],"class_list":["post-249769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-teatro"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/249769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=249769"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/249769\/revisions"}],"predecessor-version":[{"id":249770,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/249769\/revisions\/249770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/143137"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=249769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=249769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=249769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}