{"id":251707,"date":"2025-10-16T13:02:03","date_gmt":"2025-10-16T11:02:03","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=251707"},"modified":"2025-10-16T13:02:03","modified_gmt":"2025-10-16T11:02:03","slug":"fa-tappa-ad-ostuni-la-mostra-su-gaza-di-22-fotoreporter-premiati-con-limpact","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/fa-tappa-ad-ostuni-la-mostra-su-gaza-di-22-fotoreporter-premiati-con-limpact\/","title":{"rendered":"Fa tappa ad Ostuni la mostra su Gaza di 22 fotoreporter premiati con l\u2019Impact"},"content":{"rendered":"<p>Domenica 19 ottobre, alle 19, nella galleria House of Lucie di Ostuni (Br), sar\u00e0 inaugurata la mostra \u201cEyes in Gaza\u201d, esposizione itinerante che presenta le fotografie e i feed Instagram di ventidue fotoreporter che lavorano nella Striscia di Gaza.<\/p>\n<p>Organizzata da La Lucie Foundation, curata da Alice Dison e Theo Carol, questa iniziativa propone un resoconto personale degli eventi attuali esaltando il potere e l\u2019utilit\u00e0 dei social media che continuano a rappresentare un&#8217;importante via di diffusione e cambiamento. Gli scatti esposti offrono uno sguardo intimo attraverso l&#8217;obiettivo dei fotoreporter che hanno vissuto in prima persona il conflitto israelo-palestinese: Dawoud AboAlkas, Samar Abu Elouf, AbdelHakeem Abu Riash, Mohammed Al Masri, Saher Alghorra, Loay Ayyoub, Motaz Azaiza, Mohammed Baba, Mahmoud Bassam, Mohammed Dahman, Majdi Fathi, Mahmud Hams, Ahmad Hasaballah, Mohammed Jadallah Salem, Suhail Nassar, Haitham Nuralden, Yasser Qudih, Mohammed Talatene, Bashar Taleb, Mohammed Zaanoun, Ahmed Zakot e Abed Zagout.<\/p>\n<p>Questi fotografi palestinesi sono stati onorati congiuntamente nel 2023 con il prestigioso riconoscimento del \u201cLucie Impact Award\u201d.<br \/>\nNella ultraventennale attivit\u00e0 dei Lucie Awards, lo specifico riconoscimento \u201cImpact\u201d \u00e8 stato istituito nel 2018 per dare rilevanza alle immagini dei fotografi che fossero riusciti a creare una forte consapevolezza nella societ\u00e0 sulle pi\u00f9 importanti questioni sociali, culturali e umanitarie. Tra i vincitori delle passate edizioni figurano John Moore, Tyler Hicks, Malike Sidibe, Fabio Bucciarelli, Paul Ratje e Lynsey Addario<\/p>\n<p>Nello specifico, questo gruppo di fotografi \u00e8 stato premiato per avere documentato in prima linea gli eventi di Gaza e per avere contribuito alla comprensione collettiva di quella situazione non mediata da manipolazioni o interpretazioni. Mettendo a repentaglio la propria vita, queste venti persone sono riuscite a trasmettere in tempo reale a migliaia di persone in tutto il mondo immagini inedite di un conflitto in rapida evoluzione.<\/p>\n<p>Sono circa 50 le opere esposte, ognuna delle quali rappresenta un segmento di una storia complessiva; un momento di un conflitto fra i pi\u00f9 controversi e complessi della storia moderna. Queste sono state anche la scenografia della serata evento dello scorso 26 settembre \u201cWhats remain.A Mater&#8217;s War\/La Storia di una madre di Gaza\u201d svoltasi nel Chiostro di San Francesco Ostuni e organizzata da House of Lucie.<\/p>\n<p>La mostra rimarr\u00e0 aperta fino al prossimo 16 novembre (dal mercoled\u00ec al sabato dalle 18 alle 21 e la domenica dalle 10 alle 13) e sar\u00e0 corredata in tutto questo periodo da eventi correlati al tema fotografico della mostra stessa e, in generale, al tema della guerra. Fra questi eventi, in particolare ricordiamo la serata sociale \u201cVersi in Lucie\u201d (23 ottobre) che far\u00e0 dialogare la Fotografia con la Poesia e la presentazione di due opere di Arte Contemporanea dell\u2019artista serba Biljana Bubnjevic (2 novembre) che saranno presenti in Galleria fino al termine della mostra fotografica.<\/p>\n<p>&nbsp;<\/p>\n<p>House of Lucie \u2013 Corso Garibaldi, 164 \u2013 Ostuni (Br)<br \/>\nInfo: 3513463642<br \/>\nInizio presentazione: 19.00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 19 ottobre, alle 19, nella galleria House of Lucie di Ostuni (Br), sar\u00e0 inaugurata la mostra \u201cEyes in Gaza\u201d, esposizione itinerante che presenta le fotografie e i feed Instagram di ventidue fotoreporter che lavorano nella Striscia di Gaza. Organizzata da La Lucie Foundation, curata da Alice Dison e Theo Carol, questa iniziativa propone un resoconto personale degli eventi attuali esaltando il potere e l\u2019utilit\u00e0 dei social media che continuano a rappresentare un&#8217;importante via di diffusione e cambiamento. Gli scatti esposti offrono uno sguardo intimo attraverso l&#8217;obiettivo dei fotoreporter che hanno vissuto in prima persona il conflitto israelo-palestinese: Dawoud AboAlkas, Samar Abu Elouf, AbdelHakeem Abu Riash, Mohammed Al Masri, Saher Alghorra, Loay Ayyoub, Motaz Azaiza, Mohammed Baba, Mahmoud Bassam, Mohammed Dahman, Majdi Fathi, Mahmud Hams, Ahmad Hasaballah, Mohammed Jadallah Salem, Suhail Nassar, Haitham Nuralden, Yasser Qudih, Mohammed Talatene, Bashar Taleb, Mohammed Zaanoun, Ahmed Zakot e Abed Zagout. Questi fotografi palestinesi sono stati onorati congiuntamente nel 2023 con il prestigioso riconoscimento del \u201cLucie Impact Award\u201d. Nella ultraventennale attivit\u00e0 dei Lucie Awards,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":251708,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-251707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/251707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=251707"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/251707\/revisions"}],"predecessor-version":[{"id":251709,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/251707\/revisions\/251709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/251708"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=251707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=251707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=251707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}