{"id":251741,"date":"2025-10-16T19:53:25","date_gmt":"2025-10-16T17:53:25","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=251741"},"modified":"2025-10-17T13:29:27","modified_gmt":"2025-10-17T11:29:27","slug":"ottobre-rosa-al-morvillo-falcone-primo-incontro-di-sensibilizzazione-per-la-prevenzione-del-tumore-al-seno","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/ottobre-rosa-al-morvillo-falcone-primo-incontro-di-sensibilizzazione-per-la-prevenzione-del-tumore-al-seno\/","title":{"rendered":"Ottobre Rosa: al Morvillo Falcone primo incontro di sensibilizzazione per la prevenzione del tumore al seno"},"content":{"rendered":"<p>Si \u00e8 tenuto questa mattina, presso l\u2019Auditorium dell\u2019IPSSS \u201cF.L. Morvillo Falcone \u2013 M. Bassi\u201d di Brindisi, il primo incontro di sensibilizzazione per la prevenzione del tumore al seno, nell\u2019ambito delle iniziative promosse per Ottobre Rosa 2025.<br \/>\nL\u2019incontro, organizzato in collaborazione con la LILT (Lega Italiana per la Lotta contro i Tumori), ASL Brindisi e l\u2019Ufficio Scolastico Territoriale di Brindisi, ha avuto l\u2019obiettivo di diffondere una maggiore consapevolezza sull\u2019importanza della prevenzione e della diagnosi precoce del tumore al seno, attraverso momenti di informazione e testimonianza.<br \/>\nA portare i saluti istituzionali e a intervenire nel corso dell\u2019incontro sono stati: la Dott.ssa Irene Esposito, Dirigente Scolastico dell\u2019IPSSS \u201cF.L. Morvillo Falcone \u2013 M. Bassi\u201d e Referente LILT Brindisi, il Dott. Maurizio De Nuccio, Direttore Generale ASL Brindisi, la Dott.ssa Angela Tiziana Di Noia, Dirigente dell\u2019Ambito Territoriale di Brindisi e il Dott. Stefano Termite, Dipartimento di Prevenzione ASL Brindisi.<br \/>\nL\u2019incontro \u00e8 stato moderato dalla Prof.ssa Raffaella Lanciano, e ha visto inoltre la testimonianza della Prof.ssa Valentina Lupo, che ha portato un contributo personale e toccante sull\u2019importanza della prevenzione.<br \/>\nL\u2019evento ha rappresentato un momento di forte partecipazione e sensibilizzazione, con l\u2019obiettivo di incoraggiare sempre pi\u00f9 donne a prendersi cura della propria salute attraverso controlli regolari e stili di vita sani.<br \/>\nL\u2019iniziativa si inserisce nel pi\u00f9 ampio programma di Ottobre Rosa, mese dedicato in tutto il mondo alla lotta contro il tumore al seno, e testimonia l\u2019impegno congiunto delle istituzioni scolastiche e sanitarie del territorio nel promuovere la cultura della prevenzione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 tenuto questa mattina, presso l\u2019Auditorium dell\u2019IPSSS \u201cF.L. Morvillo Falcone \u2013 M. Bassi\u201d di Brindisi, il primo incontro di sensibilizzazione per la prevenzione del tumore al seno, nell\u2019ambito delle iniziative promosse per Ottobre Rosa 2025. L\u2019incontro, organizzato in collaborazione con la LILT (Lega Italiana per la Lotta contro i Tumori), ASL Brindisi e l\u2019Ufficio Scolastico Territoriale di Brindisi, ha avuto l\u2019obiettivo di diffondere una maggiore consapevolezza sull\u2019importanza della prevenzione e della diagnosi precoce del tumore al seno, attraverso momenti di informazione e testimonianza. A portare i saluti istituzionali e a intervenire nel corso dell\u2019incontro sono stati: la Dott.ssa Irene Esposito, Dirigente Scolastico dell\u2019IPSSS \u201cF.L. Morvillo Falcone \u2013 M. Bassi\u201d e Referente LILT Brindisi, il Dott. Maurizio De Nuccio, Direttore Generale ASL Brindisi, la Dott.ssa Angela Tiziana Di Noia, Dirigente dell\u2019Ambito Territoriale di Brindisi e il Dott. Stefano Termite, Dipartimento di Prevenzione ASL Brindisi. L\u2019incontro \u00e8 stato moderato dalla Prof.ssa Raffaella Lanciano, e ha visto inoltre la testimonianza della Prof.ssa Valentina Lupo, che ha portato un contributo personale e toccante&#8230;<\/p>\n","protected":false},"author":2,"featured_media":251744,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-251741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/251741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=251741"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/251741\/revisions"}],"predecessor-version":[{"id":251745,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/251741\/revisions\/251745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/251744"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=251741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=251741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=251741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}