{"id":253281,"date":"2025-11-13T20:32:36","date_gmt":"2025-11-13T19:32:36","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=253281"},"modified":"2025-11-16T16:14:53","modified_gmt":"2025-11-16T15:14:53","slug":"ritrovare-il-gusto-del-voto-di-francesco-daprile","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/ritrovare-il-gusto-del-voto-di-francesco-daprile\/","title":{"rendered":"Ritrovare il gusto del voto. Di Francesco D&#8217;Aprile"},"content":{"rendered":"<p>Liste d\u2019attesa infinite, strutture dei pronto soccorso al collasso, reparti che chiudono, livelli essenziali di assistenza fermi da anni. Questo nel mentre la spesa sanitaria nazionale erogata a livello privatistico raggiunge il tetto dei 41 miliardi di euro, a fronte di quasi sei milioni di italiani che rinunciano a curarsi (fonte ISTAT per l\u2019anno 2024, per il 2023 si era a quota 4,5 milioni).<br \/>\nSecondo l\u2019Osservatorio GIMBE, preso atto anche delle previsioni di impegno di spesa nel \u201ccapitolo sanit\u00e0\u201d incluso nella manovra di bilancio statale del prossimo anno (2026) licenziata da poco, nel 2028 mancheranno circa 40 miliardi di euro per garantire i servizi essenziali di assistenza.<br \/>\nUn autentico disastro sociale generato da un lento, metodico e capzioso definanziamento.<\/p>\n<p>La sopra richiamata \u00e8 una previsione economica che ha tutta l\u2019aria di una vera e propria resa che, in un paese che invecchia, dove la fragilit\u00e0 cresce ogni giorno, rappresenta una colpa politica e morale che peser\u00e0 per decenni.<br \/>\nMa la cosa che maggiormente preoccupa \u00e8 la costatazione che non si intravedono tracce di strategie di azione, una su tutte la delegittimazione dell\u2019attivit\u00e0 privatistica dei medici con un rapporto di lavoro in essere con il SSN, che dovrebbe essere esclusivo, per contrastare tale stato di cose, quasi a confermare che la sanit\u00e0 pubblica \u00e8 destinata \u201cstrategicamente\u201d a ricoprire un ruolo molto marginale nel welfare prossimo venturo.<\/p>\n<p>Cresce la povert\u00e0.<br \/>\nLa Caritas certifica la scarsa efficacia dell\u2019assegno di inclusione e supporto per la formazione e lavoro, molto meno incisivo del reddito di cittadinanza; l\u2019ISTAT registra un aumento della povert\u00e0 assoluta e relativa; il CNEL segnala servizi pubblici sempre pi\u00f9 diseguali, ponendo forte attenzione alla circostanza che a fronte di maggiori bisogni si assegnano sempre meno risorse; potere di acquisto degli stipendi ridotto in maniera considerevole.<br \/>\nLe conseguenze di tale sconfortante decadenza economica e sociale sono fin troppo evidente: pi\u00f9 precariet\u00e0, pi\u00f9 divari, quindi meno fiducia nello stato, che rischia di essere il sentimento genetico di una pericolosa riesumazione di fantasmi di un esiziale, nefasto passato che non pu\u00f2 e non deve tornare.<\/p>\n<p>Questo desolante quadro, meritevole di interventi radicali protesi al raggiungimento di una maggiore uguaglianza, di una pi\u00f9 umana giustizia sociale, viene invece scientemente dissimulato con abili operazioni di distrazione di massa.<br \/>\nIn effetti, oggi il problema vitale ed imprescindibile non \u00e8 rappresentato dalla decadenza sociale ed economica sopra richiamata, non \u00e8 rappresentato dalla stasi del comparto industriale, non \u00e8 rappresentato dall\u2019aumento del costo delle materie prime, non \u00e8 rappresentato dalle innumerevoli tematiche che rendono difficoltoso il vivere quotidiano, ma \u00e8 costituito, cos\u00ec come diffusamente propinato alla nostra attenzione, anche in maniera ossessiva attraverso tutte le strutture dei mass media, dalla modifica di alcuni articoli della nostra Costituzione che, con l\u2019approvazione della legge 30 ottobre 2025, prevedono la separazione delle carriere nella Magistratura. E poich\u00e9 tale tematica sar\u00e0 certamente sottoposta a referendum popolare, ancora per molti mesi la teatrale e dissimulante operazione di distrazione di massa continuer\u00e0 a calcare la ribalta occupando il proscenio.<\/p>\n<p>Una violenza del potere che continua ad operare, in maniera sottile, sofisticata, molto efficace. E contro questa violenza l\u2019indignazione dei pi\u00f9 sembra essersi spuntata, sostituita da una rassegnazione che \u00e8 forse il vero pericolo di quella democrazia conquistata con atroci sofferenze dai nostri padri.<\/p>\n<p>In questi giorni \u00e8 in pieno svolgimento la campagna elettorale per il rinnovo del Consiglio Regionale della Puglia e, come ovvio, anche Brindisi \u00e8 interessata a tale appuntamento.<br \/>\nLa nostra, come pi\u00f9 volte evocato, \u00e8 una citt\u00e0 che vive da anni uno stato socio economico in evidente affanno, subisce la totale mancanza di un nuovo modello di sviluppo teso alla trasformazione ecosostenibile del territorio, maggiormente legato alle proprie risorse, alle proprie storiche vocazioni, a ci\u00f2 che pi\u00f9 profondamente gli appartiene; ed \u00e8 per questo che gli indicatori di valutazione della vivibilit\u00e0 (affari e lavoro, tenore di vita, ambiente, criminalit\u00e0, disagio sociale, strutture scolastiche, sistema salute, tempo libero, ecc.) la posizionano in uno degli ultimi posti della graduatoria nazionale.<\/p>\n<p>Anche questo avvilente quadro viene, invece, \u201cscientemente dissimulato con abili operazioni di distrazione di massa\u201d rappresentati dalle tante pantomime dei politici \u201cde noantri\u201d che, con arroganza e spudoratezza, irrompono sul \u201cproscenio elettorale\u201d invadendo l\u2019opinione pubblica con roboanti notizie di imminenti interventi, di assegnazioni di \u201ccofanate\u201d di denaro pubblico.<br \/>\nAncora.<\/p>\n<p>Non pu\u00f2 che apparire mortificante attendersi opere di riqualificazione di strutture pubbliche (edifici scolastici, parchi, strade, ecc.) ridotti in degrado \u201csperando\u201d di attingere alle (im)propabili compensazioni connesse ai provvedimenti autorizzativi per impianti alimentati da fonti rinnovabili, quando per oltre quarant\u2019anni la salute pubblica, ancorch\u00e9 l\u2019intero territorio, sono stati sottoposti ad una irripetibile devastazione da parte di insediamenti industriali ad altissimo impatto ambientale senza alcun ritorno di pubblico interesse.<br \/>\nNon pu\u00f2 che sembrare mortificante assistere inermi allo scempio fatto perpetrare alla nostra citt\u00e0 con la perdita di vari enti come l\u2019Autorit\u00e0 di Sistema Portuale, la Camera di Commercio, la Banca D\u2019Italia e, per ultimo, (udite! udite!) la sede dell\u2019ex CONI, ora Sport e Salute, accorpata alla sede di Lecce.<\/p>\n<p>Con il solo pensiero di chi scrive, senza alcuna pretesa di rappresentare altri, ritengo di affermare che una netta inversione di tendenza appare imprescindibile.<br \/>\nEd ecco perch\u00e9, in occasione della prossima, ennesima tornata elettorale, ritrovare il gusto del voto, che \u00e8 una solenne cerimonia di investitura della politica che andrebbe rivalutata di pi\u00f9 e meglio, non pu\u00f2 che risultare irrinunciabile.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Francesco D&#8217;Aprile<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liste d\u2019attesa infinite, strutture dei pronto soccorso al collasso, reparti che chiudono, livelli essenziali di assistenza fermi da anni. Questo nel mentre la spesa sanitaria nazionale erogata a livello privatistico raggiunge il tetto dei 41 miliardi di euro, a fronte di quasi sei milioni di italiani che rinunciano a curarsi (fonte ISTAT per l\u2019anno 2024, per il 2023 si era a quota 4,5 milioni). Secondo l\u2019Osservatorio GIMBE, preso atto anche delle previsioni di impegno di spesa nel \u201ccapitolo sanit\u00e0\u201d incluso nella manovra di bilancio statale del prossimo anno (2026) licenziata da poco, nel 2028 mancheranno circa 40 miliardi di euro per garantire i servizi essenziali di assistenza. Un autentico disastro sociale generato da un lento, metodico e capzioso definanziamento. La sopra richiamata \u00e8 una previsione economica che ha tutta l\u2019aria di una vera e propria resa che, in un paese che invecchia, dove la fragilit\u00e0 cresce ogni giorno, rappresenta una colpa politica e morale che peser\u00e0 per decenni. Ma la cosa che maggiormente preoccupa \u00e8 la costatazione che non si&#8230;<\/p>\n","protected":false},"author":2,"featured_media":251300,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-253281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interventi"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/253281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=253281"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/253281\/revisions"}],"predecessor-version":[{"id":253286,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/253281\/revisions\/253286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/251300"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=253281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=253281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=253281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}