{"id":25453,"date":"2014-10-22T19:09:44","date_gmt":"2014-10-22T17:09:44","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=25453"},"modified":"2014-10-22T19:13:51","modified_gmt":"2014-10-22T17:13:51","slug":"dipendenti-abaco-dai-noi-risultati-lusinghieri-amareggiati-dalla-possibile-internalizzazione","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/dipendenti-abaco-dai-noi-risultati-lusinghieri-amareggiati-dalla-possibile-internalizzazione\/","title":{"rendered":"Dipendenti Abaco: &#8220;dai noi risultati lusinghieri, amareggiati dalla possibile internalizzazione&#8221;"},"content":{"rendered":"<p>&#8220;<em>Apprendiamo con un amaro sorriso le dichiarazioni del Sindaco Consales in tema di riscossione tributi e lotta all\u2019evasione<\/em>&#8220;, siamo &#8220;<em>compiaciuti per i risultati raggiunti che danno Brindisi come terza in Puglia per capacit\u00e0 di incassare le imposte<\/em>&#8221; e saremmo &#8220;<em>amareggiati se il Comune dovesse scegliere di internalizzare il servizio<\/em>&#8220;.<\/p>\n<p>Sono queste in sintesi le dichiarazioni e gli umori di 12 impiegati dell&#8217;Abaco &#8211; attuale concessionario per l\u2019accertamento e la riscossione delle entrate del Comune di Brindisi. Sono Arnese E., Barba I., Borromeo D., Curto R., De Rosa M., Gagliani M. Guadalupi I., Guadalupi L., Intiglietta M.,\u00a0 Masi A., Pampo S., Saponaro M., Tricarico A.<br \/>\nIn un comunicato stampa diffuso nella giornata di oggi, i lavoratori si dicono &#8220;<em>compiaciuti per il risultato dichiarato &#8211; emerso da fonte autorevole come il Sole 24 ore &#8211; poich\u00e9 coscienti, essendo il braccio operativo del Comune in tema di tributi locali da almeno 12 anni, che i risultati lusinghieri sono il frutto dell\u2019impegno costante e responsabile, tenuto conto della difficile situazione in cui si \u00e8 operato negli ultimi cinque anni caratterizzati dall\u2019avvicendamento di quattro diversi concessionari, con le difficolt\u00e0 operative che ne conseguono<\/em>.<\/p>\n<p>I\u00a0dipendenti di Abaco\u00a0&#8220;<em>rammentano che l\u2019impegno e la continuit\u00e0 operativa a favore del proprio Comune non sono mai venuti meno, neanche quando, per ben due volte, hanno lavorato pur senza percepire lo stipendio per diversi mesi, a causa delle ben note vicende amministrative che portarono come conseguenza la rescissione del contratto di servizio con Gestor nel 2010 e con Gema nel 2012<\/em>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;<em>Alla luce di queste considerazioni <\/em>&#8211; concludono &#8211;<em> sono molto amareggiati nel leggere che il Comune si appresterebbe ad internalizzare il servizio, qualora anche questo ulteriore esperimento di gara (il quinto) andasse deserto<\/em>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Apprendiamo con un amaro sorriso le dichiarazioni del Sindaco Consales in tema di riscossione tributi e lotta all\u2019evasione&#8220;, siamo &#8220;compiaciuti per i risultati raggiunti che danno Brindisi come terza in Puglia per capacit\u00e0 di incassare le imposte&#8221; e saremmo &#8220;amareggiati se il Comune dovesse scegliere di internalizzare il servizio&#8220;. Sono queste in sintesi le dichiarazioni e gli umori di 12 impiegati dell&#8217;Abaco &#8211; attuale concessionario per l\u2019accertamento e la riscossione delle entrate del Comune di Brindisi. Sono Arnese E., Barba I., Borromeo D., Curto R., De Rosa M., Gagliani M. Guadalupi I., Guadalupi L., Intiglietta M.,\u00a0 Masi A., Pampo S., Saponaro M., Tricarico A. In un comunicato stampa diffuso nella giornata di oggi, i lavoratori si dicono &#8220;compiaciuti per il risultato dichiarato &#8211; emerso da fonte autorevole come il Sole 24 ore &#8211; poich\u00e9 coscienti, essendo il braccio operativo del Comune in tema di tributi locali da almeno 12 anni, che i risultati lusinghieri sono il frutto dell\u2019impegno costante e responsabile, tenuto conto della difficile situazione in cui si \u00e8&#8230;<\/p>\n","protected":false},"author":2,"featured_media":25456,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1146],"class_list":["post-25453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-abaco"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/25453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=25453"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/25453\/revisions"}],"predecessor-version":[{"id":25455,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/25453\/revisions\/25455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/25456"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=25453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=25453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=25453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}