{"id":25474,"date":"2014-10-23T23:51:37","date_gmt":"2014-10-23T21:51:37","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=25474"},"modified":"2014-11-05T17:08:30","modified_gmt":"2014-11-05T16:08:30","slug":"radiazioni-video-cult-20-memories-perseus","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/radiazioni-video-cult-20-memories-perseus\/","title":{"rendered":"Radiazioni Video Cult 20: Memories &#8211; Perseus"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1557\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1-229x300.jpg\" alt=\"Radiazioni Cult\" width=\"180\" height=\"235\" data-id=\"1557\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1-229x300.jpg 229w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1.jpg 410w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a><strong>RADIAZIONI VIDEO CULT &#8211; Clip Musicali, Trailers e Cortometraggi <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Il video di &#8220;culto&#8221; di questa settimana \u00e8 &#8220;Memories&#8221; dei Perseus.<\/p>\n<p>I Perseus sono una band di power metal nata a Brindisi nel 2011.<\/p>\n<p>I Perseus vantano un sound e uno stile personale che attinge dalla tradizione dei pi\u00f9 importanti gruppi metal.<\/p>\n<p>Le liriche rappresentano una sorta di viaggio introspettivo e di esplorazione dell&#8217;animo umano.<\/p>\n<p>&nbsp;<\/p>\n<p>La band \u00e8 formata da Antonio Abate (voce), Cristian Guzzo (chitarra), Gabriele Pinto (chitarra), Alex Anelli (basso), Feliciano Lamarina (batteria).<\/p>\n<p>&nbsp;<\/p>\n<p>Nel 2014 i Perseus hanno pubblicato il primo album ufficiale &#8220;The Mystic Hands Of Fate&#8221;, edito da &#8220;Nadir Music&#8221; e prodotto da Tommy Talamanca.<\/p>\n<p>&nbsp;<\/p>\n<p>Il video di &#8220;culto&#8221; di Radiazioni Cult di questa settimana \u00e8 &#8220;Memories&#8221; dei Perseus, diretto da Piernicola Mele con la collaborazione di &#8220;Cold Flames&#8221;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Perseus \/ Memories\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/v3eSsNVmdHc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RADIAZIONI VIDEO CULT &#8211; Clip Musicali, Trailers e Cortometraggi &nbsp; Il video di &#8220;culto&#8221; di questa settimana \u00e8 &#8220;Memories&#8221; dei Perseus. I Perseus sono una band di power metal nata a Brindisi nel 2011. I Perseus vantano un sound e uno stile personale che attinge dalla tradizione dei pi\u00f9 importanti gruppi metal. Le liriche rappresentano una sorta di viaggio introspettivo e di esplorazione dell&#8217;animo umano. &nbsp; La band \u00e8 formata da Antonio Abate (voce), Cristian Guzzo (chitarra), Gabriele Pinto (chitarra), Alex Anelli (basso), Feliciano Lamarina (batteria). &nbsp; Nel 2014 i Perseus hanno pubblicato il primo album ufficiale &#8220;The Mystic Hands Of Fate&#8221;, edito da &#8220;Nadir Music&#8221; e prodotto da Tommy Talamanca. &nbsp; Il video di &#8220;culto&#8221; di Radiazioni Cult di questa settimana \u00e8 &#8220;Memories&#8221; dei Perseus, diretto da Piernicola Mele con la collaborazione di &#8220;Cold Flames&#8221; &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":25475,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[198,189,10],"tags":[192,1250],"class_list":["post-25474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-2","category-musica-2","category-video","tag-radiazioni-cult","tag-radiazioni-video-cult"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/25474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=25474"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/25474\/revisions"}],"predecessor-version":[{"id":25476,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/25474\/revisions\/25476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/25475"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=25474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=25474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=25474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}