{"id":261496,"date":"2026-05-13T18:07:35","date_gmt":"2026-05-13T16:07:35","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=261496"},"modified":"2026-05-13T22:12:01","modified_gmt":"2026-05-13T20:12:01","slug":"giornata-della-ristorazione-successo-a-brindisi-per-liniziativa-promossa-da-fipe-confcommercio-nel-plesso-calo-del-comprensivo-casale","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/giornata-della-ristorazione-successo-a-brindisi-per-liniziativa-promossa-da-fipe-confcommercio-nel-plesso-calo-del-comprensivo-casale\/","title":{"rendered":"\u201cGiornata della Ristorazione\u201d \u2013 Successo a Brindisi per l\u2019iniziativa promossa da Fipe\/Confcommercio nel plesso \u201cCal\u00f2\u201d del Comprensivo \u201cCasale\u201d"},"content":{"rendered":"<p>Ha riscosso un notevole successo l\u2019iniziativa promossa da Fipe\/Confcommercio Brindisi nel plesso scolastico \u201cCal\u00f2\u201d del Comprensivo \u201cCasale\u201d in occasione della \u201cGiornata della Ristorazione 2026\u201d.<\/p>\n<p>L\u2019evento \u201cChicchi di Futuro: Riso, risate e bont\u00e0\u201d, ha visto coinvolte due classi terze della scuola primaria.<\/p>\n<p>Dopo i saluti dei responsabili del plesso scolastico sono intervenuti il Presidente di Confcommercio Brindisi Gianni Corciulo ed il Presidente di Fipe\/Confcommercio Marco Carruezzo.<\/p>\n<p>Ha fatto seguito un coinvolgente intervento di educazione alimentare della biologa nutrizionista Francesca Marra, con momenti dedicati alla scoperta del riso, alle sue propriet\u00e0 nutrizionali e al suo ruolo in un\u2019alimentazione equilibrata.<\/p>\n<p>Il programma \u00e8 stato arricchito da un racconto delle tradizioni locali legate al riso e da attivit\u00e0 ludico-creative, tra cui giochi di gruppo e laboratori manuali, che hanno coinvolto attivamente gli alunni.<\/p>\n<p>L\u2019evento si \u00e8 concluso con un momento di condivisione e con la consegna degli attestati di partecipazione e dei gadget realizzati dai bambini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ha riscosso un notevole successo l\u2019iniziativa promossa da Fipe\/Confcommercio Brindisi nel plesso scolastico \u201cCal\u00f2\u201d del Comprensivo \u201cCasale\u201d in occasione della \u201cGiornata della Ristorazione 2026\u201d. L\u2019evento \u201cChicchi di Futuro: Riso, risate e bont\u00e0\u201d, ha visto coinvolte due classi terze della scuola primaria. Dopo i saluti dei responsabili del plesso scolastico sono intervenuti il Presidente di Confcommercio Brindisi Gianni Corciulo ed il Presidente di Fipe\/Confcommercio Marco Carruezzo. Ha fatto seguito un coinvolgente intervento di educazione alimentare della biologa nutrizionista Francesca Marra, con momenti dedicati alla scoperta del riso, alle sue propriet\u00e0 nutrizionali e al suo ruolo in un\u2019alimentazione equilibrata. Il programma \u00e8 stato arricchito da un racconto delle tradizioni locali legate al riso e da attivit\u00e0 ludico-creative, tra cui giochi di gruppo e laboratori manuali, che hanno coinvolto attivamente gli alunni. L\u2019evento si \u00e8 concluso con un momento di condivisione e con la consegna degli attestati di partecipazione e dei gadget realizzati dai bambini.<\/p>\n","protected":false},"author":2,"featured_media":261503,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-261496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/261496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=261496"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/261496\/revisions"}],"predecessor-version":[{"id":261504,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/261496\/revisions\/261504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/261503"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=261496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=261496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=261496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}