{"id":266730,"date":"2026-09-02T18:38:25","date_gmt":"2026-09-02T16:38:25","guid":{"rendered":"https:\/\/www.brundisium.net\/?p=266730"},"modified":"2026-09-02T18:53:54","modified_gmt":"2026-09-02T16:53:54","slug":"incendio-in-una-discarica-abusiva-trovate-17-bombole-di-gpl-tra-i-rifiuti","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/incendio-in-una-discarica-abusiva-trovate-17-bombole-di-gpl-tra-i-rifiuti\/","title":{"rendered":"Pericoloso incendio in una discarica abusiva: tra i rifiuti c&#8217;erano 17 bombole di GPL"},"content":{"rendered":"<p>Grave episodio di incivilt\u00e0 e potenziale pericolo per la sicurezza pubblica nel territorio di Carovigno, dove nel pomeriggio di oggi una squadra dei Vigili del Fuoco del Comando provinciale di Brindisi \u00e8 intervenuta presso le pertinenze di un casolare rurale situato in contrada San Francesco, lungo la Strada Comunale 33 Agro Vica Rovina, per un incendio sviluppatosi all\u2019interno di una discarica abusiva.<\/p>\n<p>Tra i rifiuti abbandonati era presente materiale altamente infiammabile e potenzialmente pericoloso. In particolare, i Vigili del Fuoco hanno rinvenuto circa 17 bombole e bottiglie di GPL, lasciate incustodite all\u2019aperto ed esposte agli agenti atmosferici e agli sbalzi termici. Nell\u2019area erano stati inoltre accumulati materiale edile e ponteggi in disuso.<\/p>\n<p>Il deposito incontrollato di contenitori a pressione rappresenta un serio pericolo, non soltanto per l\u2019ambiente e la fauna locale, ma anche per la sicurezza degli abitanti della zona e dei passanti. La presenza delle bombole di GPL in prossimit\u00e0 dell\u2019incendio ha inoltre aumentato sensibilmente i rischi per gli stessi operatori impegnati nelle operazioni di spegnimento e messa in sicurezza.<\/p>\n<p>L\u2019intervento dei Vigili del Fuoco, coadiuvati da unit\u00e0 speciali, \u00e8 proseguito con le delicate operazioni di bonifica e messa in sicurezza delle bombole e delle bottiglie di GPL presenti nell\u2019area. Un episodio che richiama ancora una volta l\u2019attenzione sulle gravi conseguenze dell\u2019abbandono incontrollato dei rifiuti e sui rischi che simili comportamenti possono determinare per la sicurezza dell\u2019intera collettivit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grave episodio di incivilt\u00e0 e potenziale pericolo per la sicurezza pubblica nel territorio di Carovigno, dove nel pomeriggio di oggi una squadra dei Vigili del Fuoco del Comando provinciale di Brindisi \u00e8 intervenuta presso le pertinenze di un casolare rurale situato in contrada San Francesco, lungo la Strada Comunale 33 Agro Vica Rovina, per un incendio sviluppatosi all\u2019interno di una discarica abusiva. Tra i rifiuti abbandonati era presente materiale altamente infiammabile e potenzialmente pericoloso. In particolare, i Vigili del Fuoco hanno rinvenuto circa 17 bombole e bottiglie di GPL, lasciate incustodite all\u2019aperto ed esposte agli agenti atmosferici e agli sbalzi termici. Nell\u2019area erano stati inoltre accumulati materiale edile e ponteggi in disuso. Il deposito incontrollato di contenitori a pressione rappresenta un serio pericolo, non soltanto per l\u2019ambiente e la fauna locale, ma anche per la sicurezza degli abitanti della zona e dei passanti. La presenza delle bombole di GPL in prossimit\u00e0 dell\u2019incendio ha inoltre aumentato sensibilmente i rischi per gli stessi operatori impegnati nelle operazioni di spegnimento e messa in&#8230;<\/p>\n","protected":false},"author":2,"featured_media":266731,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-266730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/266730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=266730"}],"version-history":[{"count":3,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/266730\/revisions"}],"predecessor-version":[{"id":266734,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/266730\/revisions\/266734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/266731"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=266730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=266730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=266730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}