{"id":26794,"date":"2014-11-10T01:31:30","date_gmt":"2014-11-10T00:31:30","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=26794"},"modified":"2014-11-10T14:38:04","modified_gmt":"2014-11-10T13:38:04","slug":"serie-d-np-ceglie-a-valanga-sul-corato","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/serie-d-np-ceglie-a-valanga-sul-corato\/","title":{"rendered":"Serie D: NP Ceglie a valanga sul Corato"},"content":{"rendered":"<p>FAS s.p.a. Corato 60-88 N.P. Ceglie<br \/>\nParziali: 18-23\/ 27-16\/ 10-23\/ 5-26<\/p>\n<p>Tabellino FAS s.p.a. Corato: Armenise 1, Gatta A. 17, Cusanno 3, Logoluso 13, Di Bartolomeo 10, Tosti 4, Amendolagine 8, Cannillo 2, D&#8217;Imperio 2, Monetti N.E. (Non Entrato) &#8211; All. Scaringella<\/p>\n<p>Tabellino N.P. Ceglie: Milone 11, Semerano 0, Argentiero 29, Crovace 10, Serpentino 10, Maggio N.E. (Non Entrato), Faggiano 21, Urso 7, Laneve 0, Taliente 0 &#8211; All. Caricasole G.<\/p>\n<p>Continua spedita la marcia della N.P. Ceglie nel campionato di Serie D Regionale con il quinto successo consecutivo dei ragazzi di coach Giulio Caricasole che riescono ad espugnare 60-88 un PalaLosito letteralmente infuocato.<br \/>\nGara avvincente che ha visto i locali tenere botta alla capolista per ben due quarti con Gatta e Logoluso senza dubbio sugli scudi con alte percentuali di tiro che hanno destato sicuramente non poche preoccupazioni agli spettatori cegliesi presenti sugli spalti.<br \/>\nI gialloblu, tuttavia, guidati in regia da un incontenibile Crovace, hanno risposto alla grande ai pesanti breaks coratini con Faggiano, Argentiero e Urso fra i migliori.<br \/>\nIl secondo quarto si conclude 45-39 in favore dei locali.<br \/>\nLa pausa lunga si rivela una vera manna dal cielo per la corazzata messapica con un Argentiero indemoniato dai 6,75 con ben tre triple a segno in pochi minuti che hanno ribaltato un punteggio che sicuramente non sorrideva ai messapici.<br \/>\nCon le bombe di Argentiero e un Serpentino sempre presente sotto le plance, la gara cambia improvvisamente rotta con i locali che si ritrovano nel giro di pochi minuti sotto di oltre quindici punti con i gialloblu che dilagano nel finale (+ 28) con Milone e un indomabile Argentiero che sfiora il trentello con 29 punti a referto.<br \/>\nVittoria pesantissima per la classifica che riconsegna in prima posizione la N.P. Ceglie che gi\u00e0 da domani inizier\u00e0 a preparare la difficile partita in casa contro il Poseidone Brindisi terzo in classifica in solitaria con otto punti.<\/p>\n<p>&nbsp;<\/p>\n<p>Vito Giordano<br \/>\nUfficio Stampa &#8220;N.P. Ceglie 2001&#8221;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FAS s.p.a. Corato 60-88 N.P. Ceglie Parziali: 18-23\/ 27-16\/ 10-23\/ 5-26 Tabellino FAS s.p.a. Corato: Armenise 1, Gatta A. 17, Cusanno 3, Logoluso 13, Di Bartolomeo 10, Tosti 4, Amendolagine 8, Cannillo 2, D&#8217;Imperio 2, Monetti N.E. (Non Entrato) &#8211; All. Scaringella Tabellino N.P. Ceglie: Milone 11, Semerano 0, Argentiero 29, Crovace 10, Serpentino 10, Maggio N.E. (Non Entrato), Faggiano 21, Urso 7, Laneve 0, Taliente 0 &#8211; All. Caricasole G. Continua spedita la marcia della N.P. Ceglie nel campionato di Serie D Regionale con il quinto successo consecutivo dei ragazzi di coach Giulio Caricasole che riescono ad espugnare 60-88 un PalaLosito letteralmente infuocato. Gara avvincente che ha visto i locali tenere botta alla capolista per ben due quarti con Gatta e Logoluso senza dubbio sugli scudi con alte percentuali di tiro che hanno destato sicuramente non poche preoccupazioni agli spettatori cegliesi presenti sugli spalti. I gialloblu, tuttavia, guidati in regia da un incontenibile Crovace, hanno risposto alla grande ai pesanti breaks coratini con Faggiano, Argentiero e Urso fra i&#8230;<\/p>\n","protected":false},"author":2,"featured_media":23881,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[577],"class_list":["post-26794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket","tag-ceglie"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/26794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=26794"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/26794\/revisions"}],"predecessor-version":[{"id":26796,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/26794\/revisions\/26796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/23881"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=26794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=26794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=26794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}