{"id":26983,"date":"2014-11-14T01:35:37","date_gmt":"2014-11-14T00:35:37","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=26983"},"modified":"2014-11-18T08:16:44","modified_gmt":"2014-11-18T07:16:44","slug":"radiazioni-video-art-antonio-squicciarini-trec-band","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/radiazioni-video-art-antonio-squicciarini-trec-band\/","title":{"rendered":"Radiazioni Video Art: Antonio Squicciarini &#038; Trec Band"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1557\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1-229x300.jpg\" alt=\"Radiazioni Cult\" width=\"229\" height=\"300\" data-id=\"1557\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1-229x300.jpg 229w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1.jpg 410w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/a><strong>Radiazioni Video ART &#8211; Suoni, immagini e parole<br \/>\nArtisti che Amano il Blues &#8211; Sinergia tra Musica e Immagini<br \/>\nA cura di Dino Panza<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Questa settimana:<\/p>\n<div><strong>&#8220;ANTONIO SQUICCIARINI\u00a0&amp; TREC BAND &#8211; &#8220;I WANT TO BE LOVED&#8221;.<\/strong><\/div>\n<p>&nbsp;<\/p>\n<p>Antonio Squicciarini \u00e8 nato a Bari il 4 luglio del 1957.<\/p>\n<p>Ha esordito come pittore all&#8217;et\u00e0 di 13 anni.<\/p>\n<p>L&#8217;artista pugliese \u00e8 stato protagonista di numerose mostre collettive e personali in Italia e all&#8217;estero: Palma di Majorka, Heeswijk, Amsterdam, Pittsburg, New York, ecc.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/11\/antonio-squicciarini.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-26984\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/11\/antonio-squicciarini-300x211.jpg\" alt=\"antonio-squicciarini\" width=\"300\" height=\"211\" data-id=\"26984\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/11\/antonio-squicciarini-300x211.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/11\/antonio-squicciarini.jpg 667w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Squicciarini si \u00e8 avvicinato alla scultura attraverso il maestro Bruno Cassinari, con il quale ha collaborato per circa tre anni.<\/p>\n<p>Tra le esperienze pi\u00f9 significative dell&#8217;artista, la collaborazione al film &#8220;Ginger e Fred&#8221; di Fellini, in cui Squicciarini ha disegnato le scenografie.<\/p>\n<p>&nbsp;<\/p>\n<p>Il video &#8220;I Want To Be Loved&#8221; \u00e8 stato realizzato da Beppe Merola (studioidea &#8211; agenzia di comunicazione creativa e strategica), con immagini scelte tra le opere dell&#8217;artista Antonio Squicciarini.<\/p>\n<p>&nbsp;<\/p>\n<p>Il brano del video, \u00a0interpretato dalla Trec Band, \u00e8 stato scritto per un musical nel lontano 1928.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/r_S8PIzfnBs\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Radiazioni Video ART &#8211; Suoni, immagini e parole Artisti che Amano il Blues &#8211; Sinergia tra Musica e Immagini A cura di Dino Panza &nbsp; Questa settimana: &#8220;ANTONIO SQUICCIARINI\u00a0&amp; TREC BAND &#8211; &#8220;I WANT TO BE LOVED&#8221;. &nbsp; Antonio Squicciarini \u00e8 nato a Bari il 4 luglio del 1957. Ha esordito come pittore all&#8217;et\u00e0 di 13 anni. L&#8217;artista pugliese \u00e8 stato protagonista di numerose mostre collettive e personali in Italia e all&#8217;estero: Palma di Majorka, Heeswijk, Amsterdam, Pittsburg, New York, ecc. &nbsp; Squicciarini si \u00e8 avvicinato alla scultura attraverso il maestro Bruno Cassinari, con il quale ha collaborato per circa tre anni. Tra le esperienze pi\u00f9 significative dell&#8217;artista, la collaborazione al film &#8220;Ginger e Fred&#8221; di Fellini, in cui Squicciarini ha disegnato le scenografie. &nbsp; Il video &#8220;I Want To Be Loved&#8221; \u00e8 stato realizzato da Beppe Merola (studioidea &#8211; agenzia di comunicazione creativa e strategica), con immagini scelte tra le opere dell&#8217;artista Antonio Squicciarini. &nbsp; Il brano del video, \u00a0interpretato dalla Trec Band, \u00e8 stato scritto per un musical&#8230;<\/p>\n","protected":false},"author":2,"featured_media":22232,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[198,189],"tags":[2778,1250],"class_list":["post-26983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-2","category-musica-2","tag-radiazioni-video-art","tag-radiazioni-video-cult"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/26983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=26983"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/26983\/revisions"}],"predecessor-version":[{"id":26985,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/26983\/revisions\/26985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/22232"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=26983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=26983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=26983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}