{"id":28392,"date":"2014-11-27T07:22:51","date_gmt":"2014-11-27T06:22:51","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=28392"},"modified":"2014-11-27T07:22:51","modified_gmt":"2014-11-27T06:22:51","slug":"pulli-sap-al-viceministro-bubbico-fatti-non-parole","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/pulli-sap-al-viceministro-bubbico-fatti-non-parole\/","title":{"rendered":"Pulli (Sap) al viceministro Bubbico: &#8220;fatti, non parole&#8221;"},"content":{"rendered":"<p>Il Sindacato Autonomo di Polizia in occasione dell&#8217;incontro dei consigli comunali della provincia di Brindisi aperto<br \/>\nalla cittadinanza, si appella alle Istituzioni locali per chiedere al Vice Ministro Filippo Bubbico fatti e non pi\u00f9 parole.<br \/>\nLa mancanza di lavoro, il disagio sociale e i ripetuti tentativi di riorganizzarsi da parte della malavita in questa provincia, nonostante l&#8217;impegno delle locali Autorit\u00e0 di Pubblica Sicurezza, impongono delle serie ed attente riflessioni.<\/p>\n<p>Attentati vari ad esponenti politici locali, aumento delle rapine ed innumerevoli reati predatori stanno minando la societ\u00e0 civile. Si sta delineando nella cittadinanza un senso di profonda sfiducia verso le istituzioni, come peraltro dimostrato dall&#8217;alto indice di assenteismo verificatosi nelle ultime tornate elettorali Regionali.<\/p>\n<p>Il Governo, da parte sua, piuttosto che rivendicare a gran voce in sede centrale le urgenze di questo martoriato territorio, risponde con la chiusura di Uffici della Polizia di Stato.<\/p>\n<p>&nbsp;<\/p>\n<p>A Brindisi chiuderanno i battenti la Polizia Postale e delle Comunicazioni e la Squadra Nautica.<br \/>\nI successi conseguiti nel contrasto ai reati informatici, pedo-pornografici e i tangibili segni della lotta al contrabbando piuttosto che deporre in senso positivo, determina la politica a scelte inconsulte, illogiche e scellerate.<br \/>\nLa Polizia Ferroviaria, nonostante i numerosi richiami ad un&#8217;attenzione maggiore per concrete problematiche di ordine e sicurezza pubblica per il transito e stazionamento di materiali esplodenti, piuttosto che veder potenziato l&#8217;organico che riesca a vigilare su tutti i turni, questo Governo miope ed insano ha ritenuto di doverlo declassare. Ormai lo scalo ferroviario \u00e8 terra di nessuno.<\/p>\n<p>&nbsp;<br \/>\nOccorre, inoltre, potenziare le Volanti della Questura di Brindisi, perch\u00e9 una sola pattuglia non \u00e8 in grado di assicurare un controllo capillare del territorio.<br \/>\nI Commissariati di Mesagne e Ostuni stanno anche peggio in quanto a risorse umane e strumentali.<br \/>\nLa Polizia Stradale non riesce neanche a coprire le arterie stradali di competenza.<br \/>\nI numerosi richiami all&#8217;allarme terrorismo dovrebbe determinare la politica ad adottare negli scali portuali ed aeroportuali strategie di maggior efficacia ed efficienza. Invece, &#8230;. NULLA, impera solo la politica &#8220;del gambero&#8221;.<br \/>\nLa politica risponda con i fatti, basta ai proclami e alle passerelle. Vogliamo fatti: solo fatti.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Francesco Pulli<\/strong><br \/>\n<strong> Segretario Nazionale SAP<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Sindacato Autonomo di Polizia in occasione dell&#8217;incontro dei consigli comunali della provincia di Brindisi aperto alla cittadinanza, si appella alle Istituzioni locali per chiedere al Vice Ministro Filippo Bubbico fatti e non pi\u00f9 parole. La mancanza di lavoro, il disagio sociale e i ripetuti tentativi di riorganizzarsi da parte della malavita in questa provincia, nonostante l&#8217;impegno delle locali Autorit\u00e0 di Pubblica Sicurezza, impongono delle serie ed attente riflessioni. Attentati vari ad esponenti politici locali, aumento delle rapine ed innumerevoli reati predatori stanno minando la societ\u00e0 civile. Si sta delineando nella cittadinanza un senso di profonda sfiducia verso le istituzioni, come peraltro dimostrato dall&#8217;alto indice di assenteismo verificatosi nelle ultime tornate elettorali Regionali. Il Governo, da parte sua, piuttosto che rivendicare a gran voce in sede centrale le urgenze di questo martoriato territorio, risponde con la chiusura di Uffici della Polizia di Stato. &nbsp; A Brindisi chiuderanno i battenti la Polizia Postale e delle Comunicazioni e la Squadra Nautica. I successi conseguiti nel contrasto ai reati informatici, pedo-pornografici e i&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5521,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[667,666],"class_list":["post-28392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-pulli","tag-sap"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/28392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=28392"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/28392\/revisions"}],"predecessor-version":[{"id":28393,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/28392\/revisions\/28393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/5521"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=28392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=28392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=28392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}