{"id":29628,"date":"2014-12-10T12:10:57","date_gmt":"2014-12-10T11:10:57","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=29628"},"modified":"2014-12-24T19:58:29","modified_gmt":"2014-12-24T18:58:29","slug":"lidea-regalo-del-nuovo-teatro-verdi-metti-uno-spettacolo-sotto-lalbero","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/lidea-regalo-del-nuovo-teatro-verdi-metti-uno-spettacolo-sotto-lalbero\/","title":{"rendered":"L&#8217;idea regalo del Nuovo Teatro Verdi: &#8220;Metti uno spettacolo sotto l\u2019albero!&#8221;"},"content":{"rendered":"<p><b><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/12\/idea_regalo_NTV.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-29629\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/12\/idea_regalo_NTV-211x300.jpg\" alt=\"idea_regalo_NTV\" width=\"211\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/12\/idea_regalo_NTV-211x300.jpg 211w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/12\/idea_regalo_NTV-721x1024.jpg 721w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2014\/12\/idea_regalo_NTV.jpg 1200w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/a>L\u2019idea<\/b>.<\/p>\n<p>A teatro si ride, si pensa, si sogna; quest\u2019anno sotto l&#8217;albero arriva anche l\u2019emozione di uno spettacolo. Un\u2019idea fuori dal comune, originale e alla portata di tutti, per un regalo speciale da fare in famiglia o agli amici: i biglietti degli appuntamenti in cartellone diventano una elegante confezione regalo grazie alla cartolina pop up che riproduce il prospetto del vecchio <b>Teatro Verdi<\/b>, un monumento della storia della nostra citt\u00e0. L\u2019idea di regalare uno o pi\u00f9 spettacoli del teatro \u00e8 intanto originale e in pi\u00f9 permette di cogliere nel segno, aiutando a districare il difficile dilemma di cosa regalare, in particolare a Natale.<br \/>\n<b>Prosa<\/b>, <b>musical<\/b>, <b>musica<\/b>, <b>circo<\/b>, <b>family show<\/b> e, per i pi\u00f9 piccoli e le famiglie, le \u00ab<b>Domeniche a teatro<\/b>\u00bb, tanti imperdibili titoli che creano imbarazzo nella scelta per un regalo di qualit\u00e0. Per consentire a tutti di acquistare la \u201cstrenna culturale\u201d, la biglietteria del \u00ab<b>Nuovo Teatro Verdi<\/b>\u00bb \u00e8 a disposizione del pubblico tutti i giorni <b>dal luned\u00ec al venerd\u00ec<\/b> (escluso i festivi) <b>dalle ore 11 alle 13<\/b> e <b>dalle 16.30 alle 19<\/b>. <b>Info 0831 229 230 oppure 0831 562 554<\/b>.<\/p>\n<p><b>La stagione<\/b>.<\/p>\n<p>La <b>stagione <\/b>in corso del \u00ab<b>Nuovo Teatro Verdi<\/b>\u00bb spazia dalla grande prosa dei maestri del teatro come <b>Eduardo De Filippo<\/b> (<b>\u00abIl sindaco del rione Sanit\u00e0\u00bb<\/b> con<b> Eros Pagni<\/b>), <b>William Shakespeare<\/b> (<b>\u00abRe Lear\u00bb <\/b>con <b>Michele Placido<\/b>) e <b>Carlo Goldoni<\/b> (<b>\u00abServo per due\u00bb <\/b>con <b>Pierfrancesco Favino<\/b> e gli attori del <b>\u00abGruppo Danny Rose\u00bb<\/b>) alla tensione morale di un indimenticato intellettuale del Novecento come <b>Leonardo Sciascia<\/b> (<b>\u00abL\u2019Onorevole\u00bb <\/b>con <b>Enzo Vetrano<\/b>, <b>Laura Marinoni <\/b>e <b>Stefano Randisi<\/b>). In cartellone grandi interpreti della scena oltre ad alcuni volti apprezzati del cinema e della tv come <b>Rocco Papaleo<\/b>, protagonista di una commedia musicale, la sua <b>\u00abPiccola impresa meridionale\u00bb<\/b>, che unisce aneddoti personali e canzoni, storie buffe e racconti poetici, o <b>Antonio Albanese<\/b> che rif\u00e0 il verso ai suoi celebri e storici <b>\u00abPersonaggi\u00bb<\/b>.<\/p>\n<p>La stagione coniuga i generi con il suo originale percorso tra tradizione e innovazione: dal musical con <b>\u00abSpring Awakening\u00bb<\/b> che ha rappresentato per Broadway una vera opera generazionale, alla magia del circo contemporaneo con la musica e i colori del <b>\u00abCircus Klezmer\u00bb<\/b>.<\/p>\n<p>E poi ancora la danza con un classico della tradizione russa come <b>\u00abIl Lago dei Cigni\u00bb<\/b>, la musica per cinema con un omaggio all\u2019immortale e sconfinato repertorio di <b>Ennio Morricone<\/b>, il poema epico dell\u2019<b>\u00abOrlando\u00bb<\/b> rivisitato in chiave pop dalla <b>\u00abCompagnia del Sole\u00bb<\/b>, e infine, in chiusura di stagione, una <b>\u00abCarmen\u00bb<\/b> \u201cnapoletana\u201d riscritta da <b>Enzo Moscato<\/b>, tra i capifila della cosiddetta drammaturgia post-eduardiana, e riletta dalla multietnica <b>\u00abOrchestra di Piazza Vittorio\u00bb<\/b> con <b>Iaia Forte<\/b> e <b>Roberto De Francesco<\/b> in scena.<\/p>\n<p>&nbsp;<\/p>\n<p>La stagione 2014-2015 su <b><a title=\"http:\/\/www.fondazionenuovoteatroverdi.it\/\" href=\"http:\/\/www.fondazionenuovoteatroverdi.it\/\">www.fondazionenuovoteatroverdi.it<\/a><\/b>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019idea. A teatro si ride, si pensa, si sogna; quest\u2019anno sotto l&#8217;albero arriva anche l\u2019emozione di uno spettacolo. Un\u2019idea fuori dal comune, originale e alla portata di tutti, per un regalo speciale da fare in famiglia o agli amici: i biglietti degli appuntamenti in cartellone diventano una elegante confezione regalo grazie alla cartolina pop up che riproduce il prospetto del vecchio Teatro Verdi, un monumento della storia della nostra citt\u00e0. L\u2019idea di regalare uno o pi\u00f9 spettacoli del teatro \u00e8 intanto originale e in pi\u00f9 permette di cogliere nel segno, aiutando a districare il difficile dilemma di cosa regalare, in particolare a Natale. Prosa, musical, musica, circo, family show e, per i pi\u00f9 piccoli e le famiglie, le \u00abDomeniche a teatro\u00bb, tanti imperdibili titoli che creano imbarazzo nella scelta per un regalo di qualit\u00e0. Per consentire a tutti di acquistare la \u201cstrenna culturale\u201d, la biglietteria del \u00abNuovo Teatro Verdi\u00bb \u00e8 a disposizione del pubblico tutti i giorni dal luned\u00ec al venerd\u00ec (escluso i festivi) dalle ore 11 alle 13 e&#8230;<\/p>\n","protected":false},"author":2,"featured_media":29629,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[198,162],"tags":[101],"class_list":["post-29628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-2","category-teatro","tag-nuovo-teatro-verdi"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/29628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=29628"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/29628\/revisions"}],"predecessor-version":[{"id":29630,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/29628\/revisions\/29630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/29629"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=29628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=29628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=29628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}