{"id":31814,"date":"2015-01-09T16:15:53","date_gmt":"2015-01-09T15:15:53","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=31814"},"modified":"2015-01-15T08:01:15","modified_gmt":"2015-01-15T07:01:15","slug":"la-cittadella-della-ricerca-deve-tornare-volano-economico-sociale-culturale-e-ambientale-del-territorio","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/la-cittadella-della-ricerca-deve-tornare-volano-economico-sociale-culturale-e-ambientale-del-territorio\/","title":{"rendered":"La Cittadella della Ricerca deve tornare volano economico, sociale, culturale e ambientale del territorio"},"content":{"rendered":"<p>Il comprensorio della Cittadella della Ricerca, ospita circa 400 persone che, a diverso titolo e mansione, si occupano di ricerca, formazione e servizi tecnologici avanzati. Queste persone da oltre vent\u2019anni lavorano in differenti strutture quali enti pubblici di ricerca, universit\u00e0, consorzi, laboratori di ricerca di aziende private, enti di formazione o societ\u00e0 di servizi. Ciascuno nel proprio ambito quotidianamente \u00e8 impegnato a competere e confrontarsi in contesti internazionali.<\/p>\n<p>&nbsp;<\/p>\n<p>Il comprensorio \u00e8 una realt\u00e0 importante per il Sud Italia e si richiama a importanti esperienze europee: Sophia Antipolis, Lovanio, Valencia, ma anche italiane: Trieste, Catania, e il Chilometro Rosso di Bergamo; senza contare gli Stati Uniti dove nei parchi scientifici trovano impiego 380.000 lavoratori.<br \/>\nIn tutto il mondo i parchi scientifici e tecnologici (PST) sono luoghi che riuniscono i tre elementi principali, individuati a livello globale come i motori dell\u2019innovazione economica sociale e culturale: la ricerca, l\u2019educazione e le imprese. La AURP (association of university research park) ha calcolato che nei parchi scientifici USA ogni posto di lavoro genera 2,57 posti di lavoro sul sistema produttivo.<\/p>\n<p>&nbsp;<\/p>\n<p>Circa 20 anni fa il comprensorio della Cittadella della Ricerca \u00e8 stata una occasione importante per gli, allora, giovani laureati. Occasione di una buona occupazione che ha consentito a molti di loro di restare sul territorio e non essere costretti ad emigrare.<br \/>\nOggi tuttavia sembra esaurita la spinta propulsiva e l\u2019attenzione di tutte le forze sociali su tale contesto.<br \/>\nA Brindisi, in una situazione di depressione economica e di crisi sociale la realt\u00e0 della Cittadella pu\u00f2 fare da volano allo sviluppo non solo economico ma anche sociale, culturale e alla difesa dell\u2019ambiente.<br \/>\nSoprattutto il comprensorio della Cittadella pu\u00f2 essere occasione di buona e utile occupazione, come lo \u00e8 stata per noi a suo tempo, per frenare la nuova ondata di migrazione che porta via la parte migliore dei nostri giovani e impoverisce sempre di pi\u00f9 il nostro territorio e le nostre famiglie che tanti sacrifici hanno investito nella loro formazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Per dare un contributo di analisi, proposte, soluzioni e azioni il 18 dicembre 2014 un gruppo di \u201ccittadini della cittadella\u201d, che da anni lavorano nel comprensorio (ricercatori, professori, tecnici, funzionari), promuovono la costituzione di un Comitato, denominato #iolavoroincittadella#.<br \/>\nDue i livelli di azione:<br \/>\nInterloquire con gli enti locali per contribuire a sviluppare una progettualit\u00e0 condivisa a medio e lungo termine, che si ponga obiettivi di sviluppo territoriale sostenibile, inclusivo e messa in rete;<br \/>\nMigliorare la vivibilit\u00e0, accessibilit\u00e0, attrattivit\u00e0, funzionalit\u00e0, sicurezza, sostenibilit\u00e0 del comprensorio affrontando i problemi di viabilit\u00e0, condivisione degli spazi comuni, servizi, connettivit\u00e0, accessibilit\u00e0, mobilit\u00e0 e informazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Il comitato ritiene essenziale la presenza ed il rilancio nel comprensorio della cittadella degli enti pubblici di ricerca prime tra tutte le Universit\u00e0. Non \u00e8 tanto importante edificare nuovi edifici, ma riqualificare gli esistenti e sviluppare nuove soluzioni per l\u2019edilizia, l\u2019energia, la mobilit\u00e0. Il comitato auspica che la Cittadella sia luogo di nascita e incubazione di brillanti Startup e attrattivo per le imprese innovative, generando crescenti opportunit\u00e0 di lavoro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il comprensorio della Cittadella della Ricerca, ospita circa 400 persone che, a diverso titolo e mansione, si occupano di ricerca, formazione e servizi tecnologici avanzati. Queste persone da oltre vent\u2019anni lavorano in differenti strutture quali enti pubblici di ricerca, universit\u00e0, consorzi, laboratori di ricerca di aziende private, enti di formazione o societ\u00e0 di servizi. Ciascuno nel proprio ambito quotidianamente \u00e8 impegnato a competere e confrontarsi in contesti internazionali. &nbsp; Il comprensorio \u00e8 una realt\u00e0 importante per il Sud Italia e si richiama a importanti esperienze europee: Sophia Antipolis, Lovanio, Valencia, ma anche italiane: Trieste, Catania, e il Chilometro Rosso di Bergamo; senza contare gli Stati Uniti dove nei parchi scientifici trovano impiego 380.000 lavoratori. In tutto il mondo i parchi scientifici e tecnologici (PST) sono luoghi che riuniscono i tre elementi principali, individuati a livello globale come i motori dell\u2019innovazione economica sociale e culturale: la ricerca, l\u2019educazione e le imprese. La AURP (association of university research park) ha calcolato che nei parchi scientifici USA ogni posto di lavoro genera 2,57&#8230;<\/p>\n","protected":false},"author":2,"featured_media":12740,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1900],"class_list":["post-31814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cittadella-della-ricerca"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/31814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=31814"}],"version-history":[{"count":3,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/31814\/revisions"}],"predecessor-version":[{"id":31819,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/31814\/revisions\/31819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/12740"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=31814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=31814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=31814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}