{"id":42604,"date":"2015-05-14T23:58:51","date_gmt":"2015-05-14T21:58:51","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=42604"},"modified":"2015-05-18T23:34:22","modified_gmt":"2015-05-18T21:34:22","slug":"radiazioni-video-cult-36-balla-piu-di-prima-the-black-spot","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/radiazioni-video-cult-36-balla-piu-di-prima-the-black-spot\/","title":{"rendered":"Radiazioni Video Cult 36: Balla pi\u00f9 di prima &#8211; The Black Spot"},"content":{"rendered":"<p style=\"text-align: left;\"><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1557\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1-229x300.jpg\" alt=\"Radiazioni Cult\" width=\"180\" height=\"235\" data-id=\"1557\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1-229x300.jpg 229w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2013\/12\/382910_108821532624464_1098603662_n1.jpg 410w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a><strong>Radiazioni Video Cult &#8211; Clip musicali, trailers e cortometraggi<br \/>\nA cura di Marco Greco<\/strong><\/p>\n<p>Questa settimana:<br \/>\n<strong>Balla pi\u00f9 di prima &#8211; The Black Spot<\/strong><br \/>\n&#8220;Maggio made in Italy&#8221; Solo artisti indipendenti<\/p>\n<p>&nbsp;<br \/>\nThe Black Spot sono un gruppo di alternative rock della provincia brindisina.<\/p>\n<p>&nbsp;<\/p>\n<p>Le sonorit\u00e0 prendono spunto dal pop, fino a sviluppare temi vintage e psichedelici, mescolati a sonorit\u00e0 elettroniche.<\/p>\n<p>&nbsp;<\/p>\n<p>A maggio 2015 \u00e8 stato pubblicato il nuovo video &#8220;Balla pi\u00f9 di prima&#8221;, brano promosso da Radiazioni come video &#8220;Cult&#8221; della settimana<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/XE8hT7FPT4c\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Radiazioni Video Cult &#8211; Clip musicali, trailers e cortometraggi A cura di Marco Greco Questa settimana: Balla pi\u00f9 di prima &#8211; The Black Spot &#8220;Maggio made in Italy&#8221; Solo artisti indipendenti &nbsp; The Black Spot sono un gruppo di alternative rock della provincia brindisina. &nbsp; Le sonorit\u00e0 prendono spunto dal pop, fino a sviluppare temi vintage e psichedelici, mescolati a sonorit\u00e0 elettroniche. &nbsp; A maggio 2015 \u00e8 stato pubblicato il nuovo video &#8220;Balla pi\u00f9 di prima&#8221;, brano promosso da Radiazioni come video &#8220;Cult&#8221; della settimana &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":42605,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[189,10],"tags":[1250],"class_list":["post-42604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica-2","category-video","tag-radiazioni-video-cult"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/42604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=42604"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/42604\/revisions"}],"predecessor-version":[{"id":42606,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/42604\/revisions\/42606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/42605"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=42604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=42604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=42604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}