{"id":50044,"date":"2015-08-24T10:08:19","date_gmt":"2015-08-24T08:08:19","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=50044"},"modified":"2015-08-24T11:13:04","modified_gmt":"2015-08-24T09:13:04","slug":"la-pro-brindisi-festeggia-i-74-anni-di-rino-lecci","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/la-pro-brindisi-festeggia-i-74-anni-di-rino-lecci\/","title":{"rendered":"La Pro Brindisi festeggia i 74 anni di Rino Lecci"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2015\/08\/Rino-Lecci2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-50046\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2015\/08\/Rino-Lecci2-169x300.jpg\" alt=\"Rino Lecci2\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2015\/08\/Rino-Lecci2-169x300.jpg 169w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2015\/08\/Rino-Lecci2-576x1024.jpg 576w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2015\/08\/Rino-Lecci2.jpg 918w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a>La ProBrindisi comunica che ieri domenica 23 agosto 2015 si sono svolti i festeggiamenti per il compleanno del Presidente Rino Lecci per i suoi 74 anni tutti i soci della Pro e i tifosi di tutta la Brindisi sportiva hanno augurato un buon compleanno a Rino con diversi attestati di stima e presenziando alla festa svoltasi a Squinzano nella struttura dove \u00e8 ancora ricoverato.<\/p>\n<p>Tutti siamo fiduciosi che il Presidentissimo possa vincere la sua battaglia per tornare sugli spalti a tifare per i suoi colori.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante la serata il giovane Simone Quarta di Squinzano che ha conosciuto Rino ed in questi mesi ne ha apprezzato le qualit\u00e0 umane gli ha dedicato una poesia:<\/p>\n<p><em>Ho conosciuto una persona speciale<\/em><br \/>\n<em> famosa a livello Nazionale;<\/em><br \/>\n<em> Un uomo forte e coraggioso<\/em><br \/>\n<em> che quando presidenziava non conosceva riposo;<\/em><br \/>\n<em> Da Roma, Milano e Cosenza li sono vicino<\/em><br \/>\n<em> e tutti in coro gli gridano: &#8220;Forza Rino&#8221;;<\/em><br \/>\n<em> Ripete sempre &#8220;vabben&#8221;!!<\/em><br \/>\n<em> e tutti gli vogliono un gran ben;<\/em><br \/>\n<em> Era sempre in mezzo ai giovani<\/em><br \/>\n<em> e la sua vita la dedicava ai palloni;<\/em><br \/>\n<em> Avete capito di chi sto parlando?<\/em><br \/>\n<em> ma \u00e8 naturale di Ronaldo!!<\/em><br \/>\n<em> No, non \u00e8 il momento di scherzare<\/em><br \/>\n<em> e vogliamo che Rino Lecci ritorni a Presidenziare<\/em>!!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Comunicato stampa ProBrindisi<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ProBrindisi comunica che ieri domenica 23 agosto 2015 si sono svolti i festeggiamenti per il compleanno del Presidente Rino Lecci per i suoi 74 anni tutti i soci della Pro e i tifosi di tutta la Brindisi sportiva hanno augurato un buon compleanno a Rino con diversi attestati di stima e presenziando alla festa svoltasi a Squinzano nella struttura dove \u00e8 ancora ricoverato. Tutti siamo fiduciosi che il Presidentissimo possa vincere la sua battaglia per tornare sugli spalti a tifare per i suoi colori. &nbsp; Durante la serata il giovane Simone Quarta di Squinzano che ha conosciuto Rino ed in questi mesi ne ha apprezzato le qualit\u00e0 umane gli ha dedicato una poesia: Ho conosciuto una persona speciale famosa a livello Nazionale; Un uomo forte e coraggioso che quando presidenziava non conosceva riposo; Da Roma, Milano e Cosenza li sono vicino e tutti in coro gli gridano: &#8220;Forza Rino&#8221;; Ripete sempre &#8220;vabben&#8221;!! e tutti gli vogliono un gran ben; Era sempre in mezzo ai giovani e la sua vita&#8230;<\/p>\n","protected":false},"author":2,"featured_media":50047,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[2981,2980],"class_list":["post-50044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calcio","tag-pro-brindisi","tag-rino-lecci"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/50044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=50044"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/50044\/revisions"}],"predecessor-version":[{"id":50048,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/50044\/revisions\/50048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/50047"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=50044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=50044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=50044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}