{"id":51,"date":"2013-11-08T03:00:00","date_gmt":"2013-11-08T02:00:00","guid":{"rendered":"http:\/\/www.seltest.info\/brun\/?p=51"},"modified":"2013-11-08T13:18:00","modified_gmt":"2013-11-08T12:18:00","slug":"brindisi-due-spettacoli-thalassia-in-tournee-a-parma-e-trento","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/brindisi-due-spettacoli-thalassia-in-tournee-a-parma-e-trento\/","title":{"rendered":"Brindisi, Due spettacoli Thalassia in tourne\u00e8 a Parma e Trento"},"content":{"rendered":"<table width=\"10\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" align=\"left\" bgcolor=\"#ffffff\">\n<tbody>\n<tr>\n<td>\n<table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\" bgcolor=\"#003399\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" alt=\"\" src=\"http:\/\/www.brundisium.net\/public\/amore_alberi.jpg\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Thalassia parte in tourn\u00e8e per portare in scena due spettacoli a Parma e Trento: \u201cAspettando il vento\u201d al Festival Zona Franca &#8211; Teatro delle Briciole (Parma) venerd\u00ec 8, e \u201cStoria d&#8217;amore e alberi\u201d al Teatro Cuminetti (Trento) sabato 9 e domenica 10 novembre.<\/p>\n<p>Due appuntamenti importanti quelli in calendario per la Residenza teatrale brindisina.<\/p>\n<p>Venerd\u00ec 8 novembre la compagnia \u00e8 ospitata a Parma per partecipare ad uno dei principali appuntamenti di questa stagione, il Festival Zona Franca, con lo spettacolo vincitore del Festival Festeb\u00e0 2013, \u201cAspettando il vento\u201d. Il festival, giunto quest&#8217;anno all&#8217;undicesima edizione, raccoglie un ricco calendario di spettacoli rivolti al pubblico giovane, presentati da compagnie italiane ed europee.<br \/>\nQuesto il link con la programmazione completa del festival:<a href=\" http:\/\/www.solaresonline.it\/index.php?ling=1&amp;pg=det_ra&amp;id_rassegne=84&amp;tipo=2\"> www.solaresonline.it\/index.php?ling=1&amp;pg=det_ra&amp;id_rassegne=84&amp;tipo=2<\/a><\/p>\n<p>Sabato 9 e domenica 10 novembre, Thalassia sale sul palco del Teatro Cuminetti di Trento (Centro Servizi Culturali Santa Chiara) con lo spettacolo \u201cStoria d&#8217;amore e alberi\u201d per la rassegna dedicata ai bambini inserita nella stagione 2013-2014 \u201cAnch&#8217;io a teatro con mamma e pap\u00e0\u201d.<br \/>\nQuesto il link per conoscere tutta la programmazione: <a href=\"http:\/\/www.centrosantachiara.it\/IT\/homepage\/\">www.centrosantachiara.it\/IT\/homepage\/<\/a><\/p>\n<p>Gli spettacoli in tourn\u00e8e<\/p>\n<table width=\"10\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" align=\"RIGHT\" bgcolor=\"#ffffff\">\n<tbody>\n<tr>\n<td>\n<table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\" bgcolor=\"#003399\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" alt=\"\" src=\"http:\/\/www.brundisium.net\/public\/aspettandoilvento.jpg\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Aspettando il vento (di Luigi d&#8217;Elia e Francesco Niccolini; costruito e raccontato da Luigi d\u2019Elia<br \/>\nregia di Francesco Niccolini e Fabrizio Pugliese. Una coproduzione Thalassia, Residenza teatrale di Mesagne; Festival Internazionale di Narrazione di Arzo &#8211; Svizzera, con la collaborazione del Festival Montagne Racconta; Vincitore Festival Festeb\u00e0 2013).<\/p>\n<p>C\u2019\u00e8 Arturo, un bambino che nella vita sar\u00e0 sempre un pinguino: non c\u2019\u00e8 niente da fare, non voler\u00e0 mai. Il suo pap\u00e0 viaggia per lavoro e ora c\u2019\u00e8 una nuova casa, un nuovo paese. Il suo pap\u00e0 ha i capelli che cambiano con il vento: lisci a tramontana, ricci con lo scirocco. Nel nuovo paese c\u2019\u00e8 Caterina, una ragazzina che sa tutto degli uccelli migratori. Ed \u00e8 troppo carina&#8230; anche se ha gli occhiali e l&#8217;apparecchio sopra e sotto. E poi c\u2019\u00e8 Andrea, un bambino con una passione cos\u00ec profonda da far presagire un destino pi\u00f9 grande, misterioso e magico. Lui nella vita sar\u00e0 una rondine, non c&#8217;\u00e8 dubbio. Un universo lieve, di avventure e giochi. Nuovo, tutto da scoprire.<br \/>\nUn\u2019amicizia che ha il suono del vento tra le canne e del silenzio nella palude al tramonto. Arturo, Caterina e Andrea sembrano disegnati sull&#8217;acqua dello stagno, hanno il cielo dentro, affrontano il<br \/>\nmistero e insieme si raccontano, con la meraviglia dentro gli occhi.<\/p>\n<p>Storia d&#8217;amore e alberi (liberamente ispirato a \u201cL\u2019uomo che piantava gli alberi\u201d di Jean Giono; di Francesco Niccolini; costruito e raccontato da Luigi D\u2019Elia; Terzo classificato Premio Nazionale Eolo Awards 2011 per il Teatro Ragazzi; Menzione speciale al Festival Festeba\u0300 2011).<\/p>\n<p>La storia dello spettacolo: un messaggio urgente e necessario<br \/>\nUn piccolo uomo dal passo da pinguino entra in sala, si aggira nello spazio, chiede conferma a chiunque incontri che l\u00ec trover\u00e0 dei bambini, che quello \u00e8 un teatro, una scuola, un festival, una piazza. \u00c8 un po&#8217; confuso e soprattutto sporco. Ha una valigia recuperata chiss\u00e0 dove, tenuta insieme da spago e ricordi. Un barbone, verrebbe da pensare. Eppure quando parla sa essere molto tenero, e ti vien voglia di ascoltarlo, tanto sembra indifeso e bisognoso di aiuto. Ma chi \u00e8? Quando la sala \u00e8 definitivamente piena, guarda i bambini, tira un grosso sospiro e insieme alla sua valigia e alla sua strana andatura va in proscenio. E\u2019 evidentemente emozionato: vorrebbe parlare ma ha paura. Non trova il coraggio di iniziare. Poi, finalmente, attacca e racconta, racconta, racconta\u2026 racconta di nuvole perdute, cieli e montagne, ma soprattutto racconta di un grande uomo, piccolo giardiniere di Dio, della sua poetica resistenza e della sua ostinata generosit\u00e0. Racconta dell\u2019uomo che piantava gli alberi. Dallo spettacolo \u00e8 nato il progetto di forestazione \u201cUn bosco in Paradiso\u201d.<\/p>\n<p>Tutte le tappe della tourn\u00e8e sono raccontate nel blog di Luigi D&#8217;Elia \u201cStorie di amore e alberi\u201d, consultabile a questo link: storie-di-amore-e-di-alberi.tumblr.com<\/p>\n<p>La Residenza Teatrale \u00e8 un progetto Regione Puglia realizzato con fondi europei (Fesr 2007\/2013), attuato con il Teatro Pubblico Pugliese in collaborazione con il Comune di Mesagne.<\/p>\n<p>COMUNICATO STAMPA THALASSIA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thalassia parte in tourn\u00e8e per portare in scena due spettacoli a Parma e Trento: \u201cAspettando il vento\u201d al Festival Zona Franca &#8211; Teatro delle Briciole (Parma) venerd\u00ec 8, e \u201cStoria d&#8217;amore e alberi\u201d al Teatro Cuminetti (Trento) sabato 9 e domenica 10 novembre. Due appuntamenti importanti quelli in calendario per la Residenza teatrale brindisina. Venerd\u00ec 8 novembre la compagnia \u00e8 ospitata a Parma per partecipare ad uno dei principali appuntamenti di questa stagione, il Festival Zona Franca, con lo spettacolo vincitore del Festival Festeb\u00e0 2013, \u201cAspettando il vento\u201d. Il festival, giunto quest&#8217;anno all&#8217;undicesima edizione, raccoglie un ricco calendario di spettacoli rivolti al pubblico giovane, presentati da compagnie italiane ed europee. Questo il link con la programmazione completa del festival: www.solaresonline.it\/index.php?ling=1&amp;pg=det_ra&amp;id_rassegne=84&amp;tipo=2 Sabato 9 e domenica 10 novembre, Thalassia sale sul palco del Teatro Cuminetti di Trento (Centro Servizi Culturali Santa Chiara) con lo spettacolo \u201cStoria d&#8217;amore e alberi\u201d per la rassegna dedicata ai bambini inserita nella stagione 2013-2014 \u201cAnch&#8217;io a teatro con mamma e pap\u00e0\u201d. Questo il link per conoscere tutta&#8230;<\/p>\n","protected":false},"author":1,"featured_media":123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-51","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=51"}],"version-history":[{"count":4,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/51\/revisions"}],"predecessor-version":[{"id":126,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/51\/revisions\/126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/123"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=51"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=51"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}