{"id":53521,"date":"2015-10-10T14:34:40","date_gmt":"2015-10-10T12:34:40","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=53521"},"modified":"2015-10-10T19:15:45","modified_gmt":"2015-10-10T17:15:45","slug":"c-silver-ad-ostuni-arriva-il-ruvo","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/c-silver-ad-ostuni-arriva-il-ruvo\/","title":{"rendered":"C Silver, ad Ostuni arriva il Ruvo"},"content":{"rendered":"<p>Secondo impegno casalingo stagionale per la Cestistica Ostuni, che contro la Talos Ruvo vuole tornare alla vittoria dopo la seconda sconfitta alla seconda trasferta in terra barese, stavolta ad Altamura. I giallobl\u00f9, che davanti al pubblico del PalaGentile potranno di nuovo contare sul giovane Altavilla (ai box contro la Libertas per un fastidio al ginocchio), affronteranno una squadra, quella ruvese, ancora ferma a zero punti, ma la cui posizione in classifica non rispecchia a pieno il valore del roster.<br \/>\nRoster, quello della Talos, allenata da Marco Di Stefano, che pu\u00f2 contare su elementi di sicuro valore: innanzitutto lo statunitense Tayloe Taylor, lo scorso anno alla Diamond Foggia (21.2 punti a partita finora), ma anche l\u2019esperto Pierluigi Arbore, classe \u201980 (oltre 11 di media), il 27enne lungo argentino Leandro Bartolucci (10.3) e la coppia di esterni formata da Mario Milone, classe \u201988 (13.7 a gara) e Aldo Gatta, classe \u201992 (10.7 per match).<br \/>\nTutti atleti in grado di superare la doppia cifra di media, a dimostrazione della buona organizzazione di gioco della Talos. A questi, bisogna aggiungere l\u2019altro statunitense Lonnie Funderburke, arrivato negli ultimi giorni alla corte di coach Di Stefano, e che potrebbe anch\u2019egli prendere parte alla contesa, salvo problemi dell\u2019ultima ora.<br \/>\nPer Morena e compagni, una sfida importante, al di l\u00e0 della storica rivalit\u00e0 tra le due citt\u00e0, che trov\u00f2 il culmine tra il 2006 e il 2011 con le tante sfide tra l\u2019Assi Basket di coach Putignano e la Ruvo di Giordano prima e Zerini poi. I ragazzi di coach Vozza, protagonisti di un\u2019ottima prova contro Castellaneta al PalaGentile, devono ripetersi per conquistare i due punti, pi\u00f9 che mai fondamentali contro un\u2019avversaria diretta.<br \/>\nAd arbitrare la partita saranno Giuseppe Russo di Taranto ed Eros Marseglia di Mesagne. Per la vittoria, la societ\u00e0 giallobl\u00f9 si augura che si riempia il palasport, per dare un sostegno ad una squadra giovane ma che vuole ben comparire.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA CESTISTISCA OSTUNI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo impegno casalingo stagionale per la Cestistica Ostuni, che contro la Talos Ruvo vuole tornare alla vittoria dopo la seconda sconfitta alla seconda trasferta in terra barese, stavolta ad Altamura. I giallobl\u00f9, che davanti al pubblico del PalaGentile potranno di nuovo contare sul giovane Altavilla (ai box contro la Libertas per un fastidio al ginocchio), affronteranno una squadra, quella ruvese, ancora ferma a zero punti, ma la cui posizione in classifica non rispecchia a pieno il valore del roster. Roster, quello della Talos, allenata da Marco Di Stefano, che pu\u00f2 contare su elementi di sicuro valore: innanzitutto lo statunitense Tayloe Taylor, lo scorso anno alla Diamond Foggia (21.2 punti a partita finora), ma anche l\u2019esperto Pierluigi Arbore, classe \u201980 (oltre 11 di media), il 27enne lungo argentino Leandro Bartolucci (10.3) e la coppia di esterni formata da Mario Milone, classe \u201988 (13.7 a gara) e Aldo Gatta, classe \u201992 (10.7 per match). Tutti atleti in grado di superare la doppia cifra di media, a dimostrazione della buona organizzazione di gioco&#8230;<\/p>\n","protected":false},"author":2,"featured_media":53008,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[506,53],"class_list":["post-53521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket","tag-cestistica-ostuni","tag-ostuni"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/53521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=53521"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/53521\/revisions"}],"predecessor-version":[{"id":53523,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/53521\/revisions\/53523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/53008"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=53521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=53521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=53521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}