{"id":5480,"date":"2014-02-19T12:26:00","date_gmt":"2014-02-19T11:26:00","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=5480"},"modified":"2014-02-19T12:26:00","modified_gmt":"2014-02-19T11:26:00","slug":"domani-la-luiss-fa-tappa-a-francavilla-fontana-a-caccia-dei-migliori-talenti","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/domani-la-luiss-fa-tappa-a-francavilla-fontana-a-caccia-dei-migliori-talenti\/","title":{"rendered":"Domani la LUISS fa tappa a Francavilla Fontana a caccia dei migliori talenti"},"content":{"rendered":"<p>Gioved\u00ec 20 febbraio la LUISS Guido Carli di Roma far\u00e0 tappa a Francavilla Fontana, al <b>Liceo Classico V. Lilla<\/b>, dove incontrer\u00e0 180 studenti interessati a conoscere l\u2019offerta formativa, le diverse opportunit\u00e0 di studio, le modalit\u00e0 di ammissione e le attivit\u00e0 didattiche ed extradidattiche dell\u2019Ateneo di Confindustria, punto di riferimento scientifico e culturale in Italia e all\u2019estero per gli studenti interessati alle discipline economiche, manageriali, sociali e giuridiche.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019appuntamento sar\u00e0 l\u2019occasione per riflettere sull\u2019importanza di una scelta universitaria ragionata e consapevole che parta dalla valorizzazione del proprio talento.<\/p>\n<p>A partire dalle ore 11.00 l\u2019Ingegner<b> Roberto Costantini<\/b>, Dirigente responsabile Orientamento e Brand Awareness LUISS, presenter\u00e0 agli studenti del III e IV anno la <b>LUISS Summer School<\/b>, la scuola estiva dell\u2019Ateneo che, dal 22 giugno, per 8 settimane, permetter\u00e0 ai ragazzi di vivere una settimana full time in Universit\u00e0, partecipare a diversi moduli di insegnamento in differenti discipline &#8211; tra cui economia e business, giurisprudenza, scienze politiche e comunicazione, ingegneria, fisica, matematica e medicina &#8211; e comprendere meglio le aree di studio pi\u00f9 affini alle proprie aspirazioni e attitudini.<\/p>\n<p>Gli studenti che parteciperanno alla LUISS Summer School e che avranno frequentato assiduamente i corsi dell\u2019intera settimana estiva potranno sostenere, con <b>un anno di anticipo<\/b>, la prova di ammissione alla LUISS per l\u2019anno accademico 2015-16, guadagnando cos\u00ec l\u2019ingresso a pieno titolo nell\u2019ateneo capitolino.<\/p>\n<p>Il superamento del test sostenuto durante la LUISS Summer School non \u00e8 a graduatoria, ma si basa sul raggiungimento di una soglia prefissata. Tutti coloro che supereranno questa soglia potranno accedere alla LUISS senza ulteriori test, dopo aver conseguito il diploma di maturit\u00e0.<\/p>\n<p>L\u2019Ingegner Costantini proseguir\u00e0 poi l\u2019incontro con gli studenti del V anno del Liceo V. Lilla, presentando l\u2019offerta formativa dell\u2019Ateneo e il <b>nuovo test di ingresso<\/b> ai Corsi di Laurea Triennale e a Ciclo unico per l\u2019a.a 2014-15, che si svolger\u00e0 il <b>27 marzo 2014<\/b> a Roma e in altre 29 sedi italiane e a cui \u00e8 possibile gi\u00e0 iscriversi. Per la Puglia le sedi del test sono: il Liceo Palmieri di Lecce, il Liceo Archita di Taranto, il Liceo Flacco di Bari e il Liceo Volta di Foggia.<\/p>\n<p>A partire dall\u2019a.a. 2014-15 la simulazione della nuova prova di ammissione assume particolare rilevanza, dato che il test rappresenter\u00e0 <b>l\u2019unico elemento di valutazione<\/b> per l\u2019ingresso all\u2019Universit\u00e0 LUISS. La prova di ammissione di 90 minuti, unica per tutti i corsi di laurea, consister\u00e0 in 70 domande, invece di 100.<\/p>\n<p>L\u2019iscrizione alla prova di ammissione del prossimo 27 marzo, se effettuata entro il 28 febbraio, 2014 dar\u00e0 la possibilit\u00e0 di partecipare <b>gratuitamente ad un<\/b> <b>corso di preparazione online al test di ingresso<\/b>.<\/p>\n<p>Il corso, disponibile in italiano e inglese, fornir\u00e0 al candidato il materiale didattico per esercitarsi e affinare le proprie capacit\u00e0 attraverso una serie di simulazioni e una griglia finale di risposte esatte per verificare il proprio livello di preparazione.<\/p>\n<p>&nbsp;<\/p>\n<p>La LUISS, con l\u2019obiettivo di incentivare gli studenti e le studentesse pi\u00f9 brillanti, ha previsto 5 <b>borse di studio per merito<\/b>, una per ciascuno dei cinque corsi di laurea in Scienze Politiche (italiano e inglese), Economia (italiano e inglese) e Giurisprudenza, con <b>esonero totale dal pagamento<\/b> delle rette universitarie per l\u2019intera durata del triennio o del ciclo unico in Giurisprudenza, che saranno a disposizione dei ragazzi del quinto anno, compresi coloro che hanno un reddito superiore ai limiti ISEE.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA LUISS GUIDO CARLI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 20 febbraio la LUISS Guido Carli di Roma far\u00e0 tappa a Francavilla Fontana, al Liceo Classico V. Lilla, dove incontrer\u00e0 180 studenti interessati a conoscere l\u2019offerta formativa, le diverse opportunit\u00e0 di studio, le modalit\u00e0 di ammissione e le attivit\u00e0 didattiche ed extradidattiche dell\u2019Ateneo di Confindustria, punto di riferimento scientifico e culturale in Italia e all\u2019estero per gli studenti interessati alle discipline economiche, manageriali, sociali e giuridiche. &nbsp; L\u2019appuntamento sar\u00e0 l\u2019occasione per riflettere sull\u2019importanza di una scelta universitaria ragionata e consapevole che parta dalla valorizzazione del proprio talento. A partire dalle ore 11.00 l\u2019Ingegner Roberto Costantini, Dirigente responsabile Orientamento e Brand Awareness LUISS, presenter\u00e0 agli studenti del III e IV anno la LUISS Summer School, la scuola estiva dell\u2019Ateneo che, dal 22 giugno, per 8 settimane, permetter\u00e0 ai ragazzi di vivere una settimana full time in Universit\u00e0, partecipare a diversi moduli di insegnamento in differenti discipline &#8211; tra cui economia e business, giurisprudenza, scienze politiche e comunicazione, ingegneria, fisica, matematica e medicina &#8211; e comprendere meglio le aree di studio&#8230;<\/p>\n","protected":false},"author":2,"featured_media":5481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[27,331],"class_list":["post-5480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-francavilla","tag-luiss"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/5480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=5480"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/5480\/revisions"}],"predecessor-version":[{"id":5483,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/5480\/revisions\/5483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/5481"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=5480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=5480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=5480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}