{"id":6278,"date":"2014-02-26T11:55:39","date_gmt":"2014-02-26T10:55:39","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=6278"},"modified":"2014-02-26T13:27:36","modified_gmt":"2014-02-26T12:27:36","slug":"uil-organizza-incontri-sullimposta-unica-comunale","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/uil-organizza-incontri-sullimposta-unica-comunale\/","title":{"rendered":"Uil organizza incontri sull&#8217;imposta unica comunale"},"content":{"rendered":"<p>Con l\u2019approvazione della Legge di Stabilit\u00e0 per il 2014 (legge 27 dicembre 2013, n. 147 recante Disposizioni per la formazione del bilancio annuale e pluriennale dello Stato), \u00e8 entrata in vigore dal primo gennaio di quest\u2019anno l\u2019Imposta Unica Comunale (IUC). <\/p>\n<p>Su questo importante tema il 28 febbraio prossimo, alle ore 9.30, nel Salone di rappresentanza corso Umberto n. 85 1\u00b0 piano, si svolger\u00e0 l\u2019iniziativa \u201cFormare per contrattare\u201d. <\/p>\n<p>La nuova imposta comunale, come previsto dalla legge, comprende tre differenti tributi:<br \/>\n&#8211; una parte patrimoniale corrispondente all\u2019IMU;<br \/>\n&#8211; una parte relativa ai servizi indivisibili, la TASI;<br \/>\n&#8211; una parte relativa allo smaltimento dei rifiuti, la TARI. <\/p>\n<p>Il dottor Luigi Veltro del Dipartimento Nazionale UIL delle politiche territoriali illustrer\u00e0 le novit\u00e0 introdotte da questo tributo. <\/p>\n<p>COMUNICATO STAMPA UIL BRINDISI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con l\u2019approvazione della Legge di Stabilit\u00e0 per il 2014 (legge 27 dicembre 2013, n. 147 recante Disposizioni per la formazione del bilancio annuale e pluriennale dello Stato), \u00e8 entrata in vigore dal primo gennaio di quest\u2019anno l\u2019Imposta Unica Comunale (IUC). Su questo importante tema il 28 febbraio prossimo, alle ore 9.30, nel Salone di rappresentanza corso Umberto n. 85 1\u00b0 piano, si svolger\u00e0 l\u2019iniziativa \u201cFormare per contrattare\u201d. La nuova imposta comunale, come previsto dalla legge, comprende tre differenti tributi: &#8211; una parte patrimoniale corrispondente all\u2019IMU; &#8211; una parte relativa ai servizi indivisibili, la TASI; &#8211; una parte relativa allo smaltimento dei rifiuti, la TARI. Il dottor Luigi Veltro del Dipartimento Nazionale UIL delle politiche territoriali illustrer\u00e0 le novit\u00e0 introdotte da questo tributo. COMUNICATO STAMPA UIL BRINDISI<\/p>\n","protected":false},"author":2,"featured_media":2470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1122,500],"class_list":["post-6278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-iuc","tag-uil"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/6278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=6278"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/6278\/revisions"}],"predecessor-version":[{"id":6282,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/6278\/revisions\/6282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/2470"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=6278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=6278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=6278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}