{"id":76238,"date":"2016-07-06T08:54:16","date_gmt":"2016-07-06T06:54:16","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=76238"},"modified":"2016-07-06T12:31:42","modified_gmt":"2016-07-06T10:31:42","slug":"76238","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/76238\/","title":{"rendered":"Lippolis (GI Confindustria) sul tema della sicurezza a Ostuni"},"content":{"rendered":"<p>Riceviamo e pubblichiamo integralmente una lettera del Presidente dei Giovani Imprenditori di Confindustria Brindisi, Dott. Gabriele Menotti Lippolis, sul tema della sicurezza della Citt\u00e0 di Ostuni:<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">Ill.mi<br \/>\nAngelino Alfano<br \/>\nMinistro dell\u2019Interno<br \/>\nFranco Gabrielli<br \/>\nCapo della Polizia di Stato<br \/>\nAnnunziato Vard\u00e8<br \/>\nPrefetto di Brindisi<br \/>\nRoberto Gentile<br \/>\nQuestore di Brindisi<br \/>\ne, p.c. Gianfranco Coppola<br \/>\nSindaco di Ostuni<br \/>\nGianni Albano<br \/>\nCommissario Capo Ostuni<\/p>\n<p style=\"text-align: left;\">In qualit\u00e0 di Presidente del Gruppo Giovani Imprenditori di Confindustria Brindisi mi<br \/>\nassocio all\u2019appello lanciato dal segretario nazionale del sindacato di Polizia Sap,<br \/>\nFrancesco Pulli, affinch\u00e8 la Citt\u00e0 Bianca sia annoverata tra le citt\u00e0 turistiche che<br \/>\nnecessitano in maniera indifferibile dell\u2019invio di rinforzi di Forze di Polizia.<br \/>\nIl silenzio persistente, a fronte delle sempre pi\u00f9 pressanti richieste perch\u00e9 si arrivi ad<br \/>\nuna pi\u00f9 nutrita presenza di forze dell\u2019ordine sul territorio Ostunese, sta profondamente<br \/>\nsconfortando la Citt\u00e0.<br \/>\nInfatti, poco pi\u00f9 di 40 unit\u00e0 ad Ostuni, una realt\u00e0 a forte vocazione turistica, non possono<br \/>\nrisolvere problematiche inerenti alla repressione dei reati e all\u2019ordine pubblico, in<br \/>\nconsiderazione di feste, concerti, sagre e manifestazioni di piazza che si tengono<br \/>\nquotidianamente.<br \/>\nNonostante l\u2019encomiabile lavoro svolto dal locale Commissariato dal 2 Novembre 2015 &#8211;<br \/>\ndata che ha segnato l\u2019insediamento del Commissario Capo Dottor Gianni Albano &#8211; che ha<br \/>\ngi\u00e0 fatto registrare 55 arresti e 200 deferimenti in stato di libert\u00e0, per la stagione estiva far<br \/>\nconfluire rinforzi nella Citt\u00e0 Bianca \u00e8 una concreta e reale esigenza.<br \/>\nGiunga, dunque, a gran voce anche l\u2019appello dei Giovani Imprenditori di Confindustria<br \/>\nBrindisi, affinch\u00e8 si possa risolvere un\u2019annosa questione che coinvolge una Citt\u00e0 che<br \/>\nproprio in questo periodo vede crescere in modo esponenziale la popolazione. Ci\u00f2 richiede<br \/>\nmaggiore attenzione e presidio del territorio, migliorando i livelli di sicurezza della Citt\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riceviamo e pubblichiamo integralmente una lettera del Presidente dei Giovani Imprenditori di Confindustria Brindisi, Dott. Gabriele Menotti Lippolis, sul tema della sicurezza della Citt\u00e0 di Ostuni: &nbsp; Ill.mi Angelino Alfano Ministro dell\u2019Interno Franco Gabrielli Capo della Polizia di Stato Annunziato Vard\u00e8 Prefetto di Brindisi Roberto Gentile Questore di Brindisi e, p.c. Gianfranco Coppola Sindaco di Ostuni Gianni Albano Commissario Capo Ostuni In qualit\u00e0 di Presidente del Gruppo Giovani Imprenditori di Confindustria Brindisi mi associo all\u2019appello lanciato dal segretario nazionale del sindacato di Polizia Sap, Francesco Pulli, affinch\u00e8 la Citt\u00e0 Bianca sia annoverata tra le citt\u00e0 turistiche che necessitano in maniera indifferibile dell\u2019invio di rinforzi di Forze di Polizia. Il silenzio persistente, a fronte delle sempre pi\u00f9 pressanti richieste perch\u00e9 si arrivi ad una pi\u00f9 nutrita presenza di forze dell\u2019ordine sul territorio Ostunese, sta profondamente sconfortando la Citt\u00e0. Infatti, poco pi\u00f9 di 40 unit\u00e0 ad Ostuni, una realt\u00e0 a forte vocazione turistica, non possono risolvere problematiche inerenti alla repressione dei reati e all\u2019ordine pubblico, in considerazione di feste, concerti, sagre e&#8230;<\/p>\n","protected":false},"author":4,"featured_media":16544,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3137,3138],"class_list":["post-76238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-giovani-confindustria","tag-ostuni-sicurezza"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/76238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=76238"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/76238\/revisions"}],"predecessor-version":[{"id":76241,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/76238\/revisions\/76241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/16544"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=76238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=76238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=76238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}