{"id":9180,"date":"2014-03-26T15:44:41","date_gmt":"2014-03-26T14:44:41","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=9180"},"modified":"2014-03-27T08:04:11","modified_gmt":"2014-03-27T07:04:11","slug":"raccolta-rifiuti-aimeri-in-difficolta-consales-valuta-alternative","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/raccolta-rifiuti-aimeri-in-difficolta-consales-valuta-alternative\/","title":{"rendered":"Raccolta rifiuti: Aimeri in difficolt\u00e0, Consales valuta alternative"},"content":{"rendered":"<p>Il Sindaco Mimmo Consales ha preso atto delle difficolt\u00e0 riscontrate nel confronto tra l\u2019azienda \u201cAimeri\u201d (a cui \u00e8 stato affidato con apposita ordinanza il servizio di raccolta di rifiuti a partire dal prossimo 1 aprile) e le organizzazioni sindacali ed ha convocato un vertice tra i dirigenti degli uffici comunali competenti.<\/p>\n<p>&nbsp;<\/p>\n<p>Al termine \u00e8 stato rivolto un invito perentorio alla ditta \u201cAimeri\u201d a consegnare entro le ore 12.00 di domani tutta la documentazione richiesta allo scopo di verificare la presenza di tutte le condizioni necessarie al passaggio di cantiere tra l\u2019attuale gestore del servizio e la stessa azienda.<\/p>\n<p>&nbsp;<\/p>\n<p>In mancanza di tale documentazione (comprovante, tra l\u2019altro, la disponibilit\u00e0 di locali idonei per il personale e per ospitare i mezzi), l\u2019Amministrazione Comunale si vedr\u00e0 costretta ad individuare soluzioni alternative.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA AMMINISTRAZIONE COMUNALE DI BRINDISI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Sindaco Mimmo Consales ha preso atto delle difficolt\u00e0 riscontrate nel confronto tra l\u2019azienda \u201cAimeri\u201d (a cui \u00e8 stato affidato con apposita ordinanza il servizio di raccolta di rifiuti a partire dal prossimo 1 aprile) e le organizzazioni sindacali ed ha convocato un vertice tra i dirigenti degli uffici comunali competenti. &nbsp; Al termine \u00e8 stato rivolto un invito perentorio alla ditta \u201cAimeri\u201d a consegnare entro le ore 12.00 di domani tutta la documentazione richiesta allo scopo di verificare la presenza di tutte le condizioni necessarie al passaggio di cantiere tra l\u2019attuale gestore del servizio e la stessa azienda. &nbsp; In mancanza di tale documentazione (comprovante, tra l\u2019altro, la disponibilit\u00e0 di locali idonei per il personale e per ospitare i mezzi), l\u2019Amministrazione Comunale si vedr\u00e0 costretta ad individuare soluzioni alternative. &nbsp; COMUNICATO STAMPA AMMINISTRAZIONE COMUNALE DI BRINDISI<\/p>\n","protected":false},"author":2,"featured_media":5650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1340,461],"class_list":["post-9180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-aimeri","tag-raccolta-rifiuti"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/9180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=9180"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/9180\/revisions"}],"predecessor-version":[{"id":9181,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/9180\/revisions\/9181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/5650"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=9180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=9180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=9180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}