{"id":9185,"date":"2014-03-26T15:52:48","date_gmt":"2014-03-26T14:52:48","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=9185"},"modified":"2014-03-26T15:52:48","modified_gmt":"2014-03-26T14:52:48","slug":"bonifica-micorosa-nicastro-firma-accordo-apre-fase-operativa","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/bonifica-micorosa-nicastro-firma-accordo-apre-fase-operativa\/","title":{"rendered":"Bonifica Micorosa, Nicastro: &#8220;firma accordo apre fase operativa&#8221;"},"content":{"rendered":"<p>&#8220;Sono particolarmente soddisfatto della sottoscrizione quest&#8217;oggi dell&#8217;accordo procedimentale di programma per la messa in sicurezza permanente dell&#8217;area Micorosa e delle aree Syndial esterne allo Stabilimento petrolchimico site nel SIN di Brindisi.<\/p>\n<p>In primo luogo perch\u00e9 essa \u00e8 lo step successivo rispetto alla sottoscrizione della convenzione tra Ministero dell&#8217;Ambiente, Regione Puglia, Comune di Brindisi e Sogesid Spa dello scorso dicembre che, per quell&#8217;area sposava la tesi della Regione Puglia destinando i 40mln di euro dell&#8217;Accordo Quadro, chiaramente non sufficienti per interventi sull&#8217;intero SIN, alla messa in sicurezza e bonifica della falda dell&#8217;area Micorosa, riconosciuta come maggiormente contaminata nel suolo e nelle acque di falda oltre che sorgente attiva di contaminazione verso il mare&#8221;. Cos\u00ec l&#8217;Assessore alla Qualit\u00e0 dell&#8217;Ambiente Lorenzo Nicastro in merito alla sottoscrizione del documento avvenuta oggi a Brindisi.<\/p>\n<div>\n<p>&nbsp;<\/p>\n<p>&#8220;In secondo luogo devo sottolineare il lavoro svolto dalle strutture tecniche dell&#8217;assessorato attraverso una Conferenza dei servizi che, con l&#8217;apporto di tutti i soggetti coinvolti dal progetto, ha definito con chiarezza competenze e procedure successive alla sottoscrizione di quest&#8217;oggi permettendo quindi aprire immediatamente la fase operativa.<\/p>\n<p>Voglio, inoltre, sottolineare la responsabilit\u00e0 e l&#8217;impegno di tutti i soggetti &#8211; conclude Nicastro &#8211; che su questo intervento hanno lavorato, seppure da prospettive differenti, con l&#8217;unico obiettivo di avviare finalmente la messa in sicurezza e la bonifica dell&#8217;area Micorosa&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMUNICATO STAMPA LORENZO NICASTRO &#8211; ASSESSORE REGIONALE ALL&#8217;AMBIENTE<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Sono particolarmente soddisfatto della sottoscrizione quest&#8217;oggi dell&#8217;accordo procedimentale di programma per la messa in sicurezza permanente dell&#8217;area Micorosa e delle aree Syndial esterne allo Stabilimento petrolchimico site nel SIN di Brindisi. In primo luogo perch\u00e9 essa \u00e8 lo step successivo rispetto alla sottoscrizione della convenzione tra Ministero dell&#8217;Ambiente, Regione Puglia, Comune di Brindisi e Sogesid Spa dello scorso dicembre che, per quell&#8217;area sposava la tesi della Regione Puglia destinando i 40mln di euro dell&#8217;Accordo Quadro, chiaramente non sufficienti per interventi sull&#8217;intero SIN, alla messa in sicurezza e bonifica della falda dell&#8217;area Micorosa, riconosciuta come maggiormente contaminata nel suolo e nelle acque di falda oltre che sorgente attiva di contaminazione verso il mare&#8221;. Cos\u00ec l&#8217;Assessore alla Qualit\u00e0 dell&#8217;Ambiente Lorenzo Nicastro in merito alla sottoscrizione del documento avvenuta oggi a Brindisi. &nbsp; &#8220;In secondo luogo devo sottolineare il lavoro svolto dalle strutture tecniche dell&#8217;assessorato attraverso una Conferenza dei servizi che, con l&#8217;apporto di tutti i soggetti coinvolti dal progetto, ha definito con chiarezza competenze e procedure successive alla sottoscrizione di quest&#8217;oggi permettendo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[647,33,781,277],"class_list":["post-9185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bonifiche","tag-brindisi","tag-micorosa","tag-nicastro"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/9185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=9185"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/9185\/revisions"}],"predecessor-version":[{"id":9186,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/9185\/revisions\/9186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/4664"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=9185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=9185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=9185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}