{"id":92009,"date":"2017-01-05T13:17:35","date_gmt":"2017-01-05T12:17:35","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=92009"},"modified":"2017-01-06T13:13:03","modified_gmt":"2017-01-06T12:13:03","slug":"c-silver-ostuni-espugna-bari-domenica-al-palagentile-arriva-lolimpica-cerignola","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/c-silver-ostuni-espugna-bari-domenica-al-palagentile-arriva-lolimpica-cerignola\/","title":{"rendered":"C Silver, Ostuni espugna Bari, domenica al PalaGentile arriva l\u2019Olimpica Cerignola"},"content":{"rendered":"<p>Si apre con una vittoria il 2017 della Cestistica Ostuni, che torna sul parquet a poco meno di due settimane dal successo interno contro Manfredonia e lo fa conquistando i due punti sul campo dell\u2019Adria Bari, fanalino di coda del girone pugliese di Serie C Silver. Contro Delli Carri e compagni, ultimi con una sola vittoria all\u2019attivo (e di prestigio, sul campo dell\u2019Olimpica Cerignola), \u00e8 bastato appena un quarto di gioco per chiudere le ostilit\u00e0, con i giallobl\u00f9 gi\u00e0 in vantaggio di 15 punti (14-29) alla prima sirena e di 23 alla pausa lunga (36-59).<\/p>\n<p>&nbsp;<br \/>\nL\u2019Adria, che alla vigilia del campionato sembrava aver rinforzato il proprio roster con l\u2019ingaggio di Williams (lo scorso anno a Vieste) al posto del partente Maietta, ha dovuto invece fare fronte nelle ultime settimane a parecchie defezioni tra i suoi uomini pi\u00f9 rappresentativi: le assenze di Ambruoso e soprattutto De Bellis, nella scorsa stagione protagonista della squadra che chiuse il campionato al settimo posto, hanno lasciato un vuoto incolmabile tra i baresi.<br \/>\nI ragazzi di coach Capozziello, che dopo la pausa natalizia sono tornati in campo con sacrificio e dedizione per il richiamo atletico invernale, continuano nei progressi gi\u00e0 visti alla fine del 2016: con quella di mercoled\u00ec sera, sono 5 vittorie di fila dopo il ko del derby a Ceglie. Insieme al solito Smith (24 punti e 36 di valutazione), ad un Manchisi in crescita (18 punti in 22\u2019) e a Vorzillo al massimo stagionale di punti (14 con 6 rimbalzi), il dominatore assoluto \u00e8 stato Bo Franklin: per lui un career high di 35 punti (15\/18 da due), 9 rimbalzi e 44 di valutazione.<\/p>\n<p>&nbsp;<br \/>\nPer la Cestistica per\u00f2 adesso il gioco si fa durissimo: domenica 8 gennaio al PalaGentile arriver\u00e0 l\u2019Olimpica Cerignola, avversario duro e che gi\u00e0 all\u2019andata mise in seria difficolt\u00e0 i giallobl\u00f9. L\u2019attuale 13\u00b0 posto degli uomini di coach Gesmundo, frutto di tanti infortuni durante la stagione, non deve ingannare: con il roster al completo, sulla carta i dauni sono una delle squadre pi\u00f9 attrezzate del campionato, in grado di battere chiunque. Servir\u00e0 un palasport bollente e stracolmo per spingere i nostri ragazzi ad una vittoria che sarebbe importantissima anche per il morale, a 6 giorni dalla sfida di sabato 14 al Paladileo contro la capolista Udas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>TABELLINO (<a href=\"http:\/\/fip-web.azurewebsites.net\/MatchStats.aspx?ID=48&amp;MID=8640&amp;rg=PU\">al link le statistiche complete<\/a>)<\/p>\n<p>Adria Bari \u2013 Cestistica Ostuni 74-100 (14-29; 36-59; 57-75)<br \/>\nBARI: Solla 2, Quaranta 2, Loprieno 10, Delli Carri 15, Posa, Williams 21, Albanese 15, Esposito 7, Bernardi, Armenise 2. Coach: De Giglio.<br \/>\nOSTUNI: Smith 24, Mihalich 4, Faraci, Manchisi 18, Franklin 35, Teofilo 2, Masciulli, Calisi 3, Petraroli, Vorzillo 14. Coach: Capozziello.<br \/>\nARBITRI: Menelao (BA), Ceo (BA).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Ufficio stampa e comunicazione \u2013 CESTISTICA OSTUNI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si apre con una vittoria il 2017 della Cestistica Ostuni, che torna sul parquet a poco meno di due settimane dal successo interno contro Manfredonia e lo fa conquistando i due punti sul campo dell\u2019Adria Bari, fanalino di coda del girone pugliese di Serie C Silver. Contro Delli Carri e compagni, ultimi con una sola vittoria all\u2019attivo (e di prestigio, sul campo dell\u2019Olimpica Cerignola), \u00e8 bastato appena un quarto di gioco per chiudere le ostilit\u00e0, con i giallobl\u00f9 gi\u00e0 in vantaggio di 15 punti (14-29) alla prima sirena e di 23 alla pausa lunga (36-59). &nbsp; L\u2019Adria, che alla vigilia del campionato sembrava aver rinforzato il proprio roster con l\u2019ingaggio di Williams (lo scorso anno a Vieste) al posto del partente Maietta, ha dovuto invece fare fronte nelle ultime settimane a parecchie defezioni tra i suoi uomini pi\u00f9 rappresentativi: le assenze di Ambruoso e soprattutto De Bellis, nella scorsa stagione protagonista della squadra che chiuse il campionato al settimo posto, hanno lasciato un vuoto incolmabile tra i baresi. I ragazzi&#8230;<\/p>\n","protected":false},"author":2,"featured_media":84987,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[506,53],"class_list":["post-92009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket","tag-cestistica-ostuni","tag-ostuni"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/92009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=92009"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/92009\/revisions"}],"predecessor-version":[{"id":92010,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/92009\/revisions\/92010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/84987"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=92009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=92009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=92009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}