{"id":92024,"date":"2017-01-05T16:25:54","date_gmt":"2017-01-05T15:25:54","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=92024"},"modified":"2017-01-08T10:50:47","modified_gmt":"2017-01-08T09:50:47","slug":"al-via-i-saldi-invernali-crescono-i-brindisini-che-sfrutteranno-gli-sconti-dieci-consigli-per-un-acquisto-consapevole","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/al-via-i-saldi-invernali-crescono-i-brindisini-che-sfrutteranno-gli-sconti-dieci-consigli-per-un-acquisto-consapevole\/","title":{"rendered":"Al via i saldi invernali: crescono i brindisini che sfrutteranno gli sconti. Dieci consigli per un acquisto consapevole"},"content":{"rendered":"<p>Oggi, 5 gennaio, anche in Provincia di Brindisi \u00e8 scattata la corsa all&#8217;offerta migliore.<br \/>\nCon l&#8217;avvio dei Saldi Invernali \u00e8 prevista una seconda ondata di corsa all&#8217;acquisto dopo il periodo natalizio.<br \/>\nSono tantissimi gli italiani che sfrutteranno i saldi.<br \/>\nDa un\u2019analisi stilata da Confcommercio-Imprese per l\u2019Italia, in collaborazione con Format Research, il 58,5% far\u00e0 shopping con i saldi invernali del 2017.<br \/>\nE&#8217; una percentuale pi\u00f9 alta di quella del 2016 (55%) ma decisamente inferiore a quella di cinque anni fa, pari a quasi il 70%.<\/p>\n<p>Nella lista dei beni preferiti i primi posti vanno ai capi di abbigliamento (92,1%), calzature (79,2%), accessori (32,1%) e biancheria intima (27,4%). Il 78,1% dei consumatori destiner\u00e0 allo shopping fino a 200 euro. Cresce inoltre la percentuale di chi considera \u201cmolto o abbastanza importante\u201d il periodo dei saldi, il 43,9% contro il 42,6% del gennaio 2016.<\/p>\n<p>Il periodo di sconti avr\u00e0 la durata canonica di 60 giorni e durer\u00e0 pertanto fino al 5 marzo.<\/p>\n<p>Per aspettare la successiva tornata di saldi estivi, bisogner\u00e0 aspettare il primo sabato del mese di luglio, che quest&#8217;anno sar\u00e0 proprio l&#8217;1.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Per una migliore fruizione delle offerte riportiamo il decalogo che ogni anni viene stilato dal coordinamento istituito dalla Confconsumatori e dall\u2019Associazione Nazionale Dalla Parte del Consumatore: un utile vademecum volto ad evitare disavventure di fine stagione.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>1) Fate attenzione ai saldi superiori al 50%, potrebbero nascondere \u201cbufale\u201d, come ad esempio la vendita di merce dell\u2019anno precedente (che ovviamente potrebbe essere ugualmente un buon affare purch\u00e9 il negoziante informi il cliente);<\/p>\n<p>&nbsp;<\/p>\n<p>2) la merce in saldo deve essere tenuta separata nettamente da quella venduta a prezzo pieno;<\/p>\n<p>&nbsp;<\/p>\n<p>3) \u00e8 obbligatorio esporre sul cartellino il vecchio prezzo, la percentuale di sconto ed il prezzo scontato;<\/p>\n<p>&nbsp;<\/p>\n<p>4) il consumatore ha diritto di provare i capi, esclusa la biancheria intima;<\/p>\n<p>&nbsp;<\/p>\n<p>5) i negozianti sono obbligati ad accettare il pagamento con carte di credito anche con i saldi; in caso di rifiuto non comprate e segnalate il caso per iscritto alla societ\u00e0 Servizi Interbancari e a un\u2019associazione di consumatori;<\/p>\n<p>&nbsp;<\/p>\n<p>6) conservate lo scontrino, perch\u00e9 costituisce prova di acquisto che obbliga il negoziante a sostituire e\/o riparare la merce difettosa o \u201cnon conforme\u201d, anche in presenza di cartelli con la dicitura che i capi in svendita non si possono cambiare;<\/p>\n<p>&nbsp;<\/p>\n<p>7) la garanzia per vizi occulti e per assenza di qualit\u00e0 promessa \u00e8 dovuta dal venditore anche nelle vendite a saldo ed \u00e8 di due anni dalla vendita secondo il Codice del Consumo;<\/p>\n<p>&nbsp;<\/p>\n<p>8) anche gli acquisti on line prevedono il diritto di recedere, senza alcuna penalit\u00e0 e senza specificare il motivo, entro 10 giorni dall\u2019acquisto, come ogni altra vendita di beni a distanza;<\/p>\n<p>&nbsp;<\/p>\n<p>9) per ogni problema, si consiglia di segnalare il fatto al locale comando dei Vigili Urbani o all\u2019assessorato comunale competente per il commercio, oltre che al coordinamento istituito dalla Confconsumatori e dall\u2019Associazione Nazionale Dalla Parte del Consumatore;<\/p>\n<p>&nbsp;<\/p>\n<p>10) fare attenzione all\u2019 \u201ceffetto sforamento\u201d: spesso, infatti, spendiamo pi\u00f9 di quanto crediamo di stare risparmiando. Utile sarebbe fare una lista degli acquisti in anticipo, e tenerla sempre sotto occhio nel fare compere.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi, 5 gennaio, anche in Provincia di Brindisi \u00e8 scattata la corsa all&#8217;offerta migliore. Con l&#8217;avvio dei Saldi Invernali \u00e8 prevista una seconda ondata di corsa all&#8217;acquisto dopo il periodo natalizio. Sono tantissimi gli italiani che sfrutteranno i saldi. Da un\u2019analisi stilata da Confcommercio-Imprese per l\u2019Italia, in collaborazione con Format Research, il 58,5% far\u00e0 shopping con i saldi invernali del 2017. E&#8217; una percentuale pi\u00f9 alta di quella del 2016 (55%) ma decisamente inferiore a quella di cinque anni fa, pari a quasi il 70%. Nella lista dei beni preferiti i primi posti vanno ai capi di abbigliamento (92,1%), calzature (79,2%), accessori (32,1%) e biancheria intima (27,4%). Il 78,1% dei consumatori destiner\u00e0 allo shopping fino a 200 euro. Cresce inoltre la percentuale di chi considera \u201cmolto o abbastanza importante\u201d il periodo dei saldi, il 43,9% contro il 42,6% del gennaio 2016. Il periodo di sconti avr\u00e0 la durata canonica di 60 giorni e durer\u00e0 pertanto fino al 5 marzo. Per aspettare la successiva tornata di saldi estivi, bisogner\u00e0 aspettare il&#8230;<\/p>\n","protected":false},"author":2,"featured_media":31331,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[33,2876],"class_list":["post-92024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-brindisi","tag-saldi"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/92024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=92024"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/92024\/revisions"}],"predecessor-version":[{"id":92025,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/92024\/revisions\/92025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/31331"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=92024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=92024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=92024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}