{"id":9226,"date":"2014-03-26T20:33:32","date_gmt":"2014-03-26T19:33:32","guid":{"rendered":"http:\/\/www.brundisium.net\/brun\/?p=9226"},"modified":"2014-03-26T21:34:57","modified_gmt":"2014-03-26T20:34:57","slug":"cisl-e-aldo-gemma-il-nuovo-segretario-della-cisl-fp-di-taranto-e-brindisi","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/cisl-e-aldo-gemma-il-nuovo-segretario-della-cisl-fp-di-taranto-e-brindisi\/","title":{"rendered":"Cisl: \u00e8 Aldo Gemma il nuovo Segretario della Cisl FP di Taranto e Brindisi"},"content":{"rendered":"<p>E&#8217; giunto al culmine il grande processo di autoriforma organizzativa che la Cisl ha avviato nel 2012, passando dalla fusione di alcune categorie, fino a giungere alla nascita di macrostrutture, regionali e territoriali, tra cui quella di Taranto-Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p><i>&#8220;Siamo i protagonisti della nascita di una nuova Cisl &#8211; <\/i>dice Aldo Gemma<i>&#8211; siamo compatti e siamo pronti a raccogliere le importanti sfide dei prossimi anni&#8221;.<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>Aldo Gemma, 48 anni, di San Pietro Vernotico (BR), sposato, due figli, gi\u00e0 atleta di livello nazionale, ha iniziato la sua carriera professionale giovanissimo, ancor prima di terminare gli studi universitari, proprio presso l&#8217;Ospedale del suo paese d&#8217;origine; e giovanissimo inizia anche la sua attivit\u00e0 sindacale, prima come RSU, poi Responsabile della sanit\u00e0 di Brindisi, e, dal 2009, come Segretario Generale di Brindisi, rivestendo, tutt\u2019ora, incarichi regionali.<\/p>\n<p>&nbsp;<\/p>\n<p><i>&#8220;Questi anni<\/i> -continua Gemma- <i>mi hanno insegnato davvero molto, e ora metter\u00f2 tutto il mio bagaglio, e tutta la mia passione civile, al servizio di queste due grandi comunit\u00e0, Taranto e Brindisi. Porter\u00f2 avanti con impegno il lavoro svolto finora, forte della qualificata collaborazione dell\u2019intero gruppo dirigente di questa grande Federazione: dovremo affrontare le riforme istituzionali, i riassetti organizzativi di servizi ed uffici, scoveremo ruberie, furbizie e sprechi, cercando alleanze affinch\u00e9 si possano trovare le soluzioni che le nostre comunit\u00e0 richiedono. Con l&#8217;impegno di tutti, combatteremo contro chi si ostina, ancora, a bloccare lo sviluppo e la voglia di ripartire dei nostri territori&#8221;<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>Insieme ad Aldo Gemma sono stati eletti oggi i componenti della Segreteria Territoriale: riconfermati Massimo Ferri e Luigi Verardi, ai quali si aggiunge il collega Giorgio Ciaccia.<\/p>\n<p>&nbsp;<\/p>\n<p>La giornata \u00e8 stata caratterizzata da una grande partecipazione e da un acceso dibattito sulla centralit\u00e0 della Pubblica Amministrazione rispetto ai processi di sviluppo e di cambiamento nelle nostre comunit\u00e0. Inoltre si sono susseguiti vari interventi di saluto e ringraziamento all&#8217;ex Segretario Cosimo Nasole, e di augurio al nuovo Segretario Generale Aldo Gemma per gli ulteriori positivi successi che lo hanno riconfermato alla guida del sindacato pi\u00f9 rappresentativo del pubblico impiego.<\/p>\n<p>Alla presenza della Segreteria Nazionale, della Segreteria Interregionale di Puglia e Basilicata e della UST di Taranto Brindisi, si sono espressi, infatti, i migliori auguri di buon lavoro ad Aldo Gemma, certi che sapr\u00e0, con rinnovato entusiasmo, affrontare una fase nuova, stare pi\u00f9 vicino ai lavoratori ed ai delegati, presidiare i territori, e farsi carico, a volte, anche di singoli problemi.<\/p>\n<p>&nbsp;<\/p>\n<p>Aldo Gemma ha ringraziato tutti per la fiducia accordata, assicurando il suo impegno quotidiano nella Cisl, nella convinzione e nella consapevolezza che ognuno debba dare un contributo doveroso verso i lavoratori e le comunit\u00e0 di Taranto e Brindisi.<br \/>\n<strong><br \/>\nCOMUNICATO STAMPA CISL FP<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; giunto al culmine il grande processo di autoriforma organizzativa che la Cisl ha avviato nel 2012, passando dalla fusione di alcune categorie, fino a giungere alla nascita di macrostrutture, regionali e territoriali, tra cui quella di Taranto-Brindisi. &nbsp; &#8220;Siamo i protagonisti della nascita di una nuova Cisl &#8211; dice Aldo Gemma&#8211; siamo compatti e siamo pronti a raccogliere le importanti sfide dei prossimi anni&#8221;. &nbsp; Aldo Gemma, 48 anni, di San Pietro Vernotico (BR), sposato, due figli, gi\u00e0 atleta di livello nazionale, ha iniziato la sua carriera professionale giovanissimo, ancor prima di terminare gli studi universitari, proprio presso l&#8217;Ospedale del suo paese d&#8217;origine; e giovanissimo inizia anche la sua attivit\u00e0 sindacale, prima come RSU, poi Responsabile della sanit\u00e0 di Brindisi, e, dal 2009, come Segretario Generale di Brindisi, rivestendo, tutt\u2019ora, incarichi regionali. &nbsp; &#8220;Questi anni -continua Gemma- mi hanno insegnato davvero molto, e ora metter\u00f2 tutto il mio bagaglio, e tutta la mia passione civile, al servizio di queste due grandi comunit\u00e0, Taranto e Brindisi. Porter\u00f2 avanti con impegno&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1505,1506],"class_list":["post-9226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-aldo-gemma","tag-cisl-fp"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/9226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=9226"}],"version-history":[{"count":1,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/9226\/revisions"}],"predecessor-version":[{"id":9227,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/9226\/revisions\/9227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/2970"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=9226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=9226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=9226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}