{"id":97603,"date":"2017-03-11T09:44:34","date_gmt":"2017-03-11T08:44:34","guid":{"rendered":"http:\/\/www.brundisium.net\/?p=97603"},"modified":"2017-03-11T10:07:02","modified_gmt":"2017-03-11T09:07:02","slug":"cocaina-pistola-e-proiettili-arrestati-moglie-e-marito","status":"publish","type":"post","link":"https:\/\/www.brundisium.net\/index.php\/cocaina-pistola-e-proiettili-arrestati-moglie-e-marito\/","title":{"rendered":"Cocaina, pistola e proiettili: arrestati moglie e marito"},"content":{"rendered":"<p><a href=\"http:\/\/www.brundisium.net\/index.php\/cocaina-pistola-e-proiettili-arrestati-moglie-e-marito\/pistola-e-coca-1\/\" rel=\"attachment wp-att-97605\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-97605\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/03\/pistola-e-coca-1-169x300.jpg\" alt=\"\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/03\/pistola-e-coca-1-169x300.jpg 169w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/03\/pistola-e-coca-1-768x1365.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/03\/pistola-e-coca-1-576x1024.jpg 576w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/03\/pistola-e-coca-1.jpg 900w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a>A Francavilla Fontana, i Carabinieri della locale Stazione in collaborazione con quelli del Nucleo Operativo e Radiomobile della locale Compagnia e del Nucleo Cinofili di Modugno (BA), nell&#8217;ambito di servizi finalizzati al contrasto del fenomeno dell&#8217;uso e spaccio della droga, hanno tratto in arresto in flagranza di reato, per detenzione ai fini di spaccio di sostanze stupefacenti, detenzione abusiva di munizioni, detenzione illegale di armi comuni da sparo, detenzione illegale di armi clandestine, i coniugi Mario Garganese, 41 anni e Loredana Marinosci, 38 anni.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Nel corso di una perquisizione domiciliare presso la loro abitazione, i Carabinieri hanno travato 5,65 grammi di cocaina (contenuta in un unico involucro sotto vuoto, rinvenuto all&#8217;interno della rete fognaria poich\u00e9 precedentemente gettato dalla donna alla vista degli operanti) nonch\u00e9 vario materiale utile per il confezionamento e pesatura, una pistola clandestina marca Bruni, mod \u201c92\u201d, cal.9 a salve, con canna modificata e matricola abrasa, comprensiva di caricatore e 2 proiettili calibro 9&#215;21 \u201cSmith &amp; Wesson, occultata nella camera da letto, il tutto sottoposto a sequestro.<\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/index.php\/cocaina-pistola-e-proiettili-arrestati-moglie-e-marito\/pistola-e-coca-4\/\" rel=\"attachment wp-att-97604\">\u00a0<\/a><\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/index.php\/cocaina-pistola-e-proiettili-arrestati-moglie-e-marito\/pistola-e-coca-1\/\" rel=\"attachment wp-att-97605\">\u00a0<\/a><\/p>\n<p><a href=\"http:\/\/www.brundisium.net\/index.php\/cocaina-pistola-e-proiettili-arrestati-moglie-e-marito\/pistola-e-coca-2\/\" rel=\"attachment wp-att-97606\">\u00a0<\/a><br \/>\n<a href=\"http:\/\/www.brundisium.net\/index.php\/cocaina-pistola-e-proiettili-arrestati-moglie-e-marito\/pistola-e-coca-3\/\" rel=\"attachment wp-att-97607\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-97607\" src=\"http:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/03\/pistola-e-coca-3-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/03\/pistola-e-coca-3-300x169.jpg 300w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/03\/pistola-e-coca-3-768x432.jpg 768w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/03\/pistola-e-coca-3-1024x576.jpg 1024w, https:\/\/www.brundisium.net\/brun\/wp-content\/uploads\/2017\/03\/pistola-e-coca-3.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u00a0Su disposizione dell&#8217;Autorit\u00e0 Giudiziaria, dopo le formalit\u00e0 di rito, gli arrestati sono stati posti agli arresti domiciliari presso la loro abitazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Francavilla Fontana, i Carabinieri della locale Stazione in collaborazione con quelli del Nucleo Operativo e Radiomobile della locale Compagnia e del Nucleo Cinofili di Modugno (BA), nell&#8217;ambito di servizi finalizzati al contrasto del fenomeno dell&#8217;uso e spaccio della droga, hanno tratto in arresto in flagranza di reato, per detenzione ai fini di spaccio di sostanze stupefacenti, detenzione abusiva di munizioni, detenzione illegale di armi comuni da sparo, detenzione illegale di armi clandestine, i coniugi Mario Garganese, 41 anni e Loredana Marinosci, 38 anni. &nbsp; &nbsp; Nel corso di una perquisizione domiciliare presso la loro abitazione, i Carabinieri hanno travato 5,65 grammi di cocaina (contenuta in un unico involucro sotto vuoto, rinvenuto all&#8217;interno della rete fognaria poich\u00e9 precedentemente gettato dalla donna alla vista degli operanti) nonch\u00e9 vario materiale utile per il confezionamento e pesatura, una pistola clandestina marca Bruni, mod \u201c92\u201d, cal.9 a salve, con canna modificata e matricola abrasa, comprensiva di caricatore e 2 proiettili calibro 9&#215;21 \u201cSmith &amp; Wesson, occultata nella camera da letto, il tutto sottoposto a&#8230;<\/p>\n","protected":false},"author":2,"featured_media":97604,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[577,243],"class_list":["post-97603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-ceglie","tag-droga"],"_links":{"self":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/97603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/comments?post=97603"}],"version-history":[{"count":2,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/97603\/revisions"}],"predecessor-version":[{"id":97610,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/posts\/97603\/revisions\/97610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media\/97604"}],"wp:attachment":[{"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/media?parent=97603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/categories?post=97603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brundisium.net\/index.php\/wp-json\/wp\/v2\/tags?post=97603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}